{"id":3612122,"date":"2024-04-23T10:52:54","date_gmt":"2024-04-23T08:52:54","guid":{"rendered":"https:\/\/www.carlton-international.com\/collaborateur\/yannick-rauscher\/"},"modified":"2025-07-03T09:52:07","modified_gmt":"2025-07-03T07:52:07","slug":"yannick-rauscher","status":"publish","type":"collaborateur","link":"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/","title":{"rendered":"Yannick RAUSCHER"},"content":{"rendered":"<p><em><strong>\u201cValorizar a Regi\u00e3o, com um aconselhamento extra!\u201d<\/strong><\/em><\/p>\n<p>Formado em administra\u00e7\u00e3o econ\u00f4mica e social, assim como em gest\u00e3o, Yannick, franco-alem\u00e3o, trabalhou doze anos em Estrasburgo como freelancer. Nativo da regi\u00e3o da Als\u00e1cia, seu conhecimento do setor o guiar\u00e1 na escolha e realiza\u00e7\u00e3o do seu projeto. Perfeitamente trilingue, Yannick \u00e9 especializado no relacionamento com os diferentes atores locais e clientes.<br \/>\nDinamismo e consci\u00eancia profissional s\u00e3o as palavras-chave que lhe trar\u00e3o serenidade em suas escolhas de investimento.<\/p>\n","protected":false},"featured_media":4310160,"menu_order":34,"template":"","class_list":["post-3612122","collaborateur","type-collaborateur","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Yannick RAUSCHER - Carlton International<\/title>\n<meta name=\"description\" content=\"Dipl\u00f4m\u00e9 en administration \u00e9conomique et sociale ainsi que management, Yannick, franco-allemand, a travaill\u00e9 douze ann\u00e9es...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yannick RAUSCHER\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T07:52:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/04\/Carlton_YR-scaled-e1713862361595.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1708\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/\",\"url\":\"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/\",\"name\":\"Yannick RAUSCHER - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/04\/Carlton_YR-scaled-e1713862361595-1.jpg\",\"datePublished\":\"2024-04-23T08:52:54+00:00\",\"dateModified\":\"2025-07-03T07:52:07+00:00\",\"description\":\"Dipl\u00f4m\u00e9 en administration \u00e9conomique et sociale ainsi que management, Yannick, franco-allemand, a travaill\u00e9 douze ann\u00e9es...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/#primaryimage\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/04\/Carlton_YR-scaled-e1713862361595-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/04\/Carlton_YR-scaled-e1713862361595-1.jpg\",\"width\":694,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yannick RAUSCHER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/pt-pt\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Yannick RAUSCHER - Carlton International","description":"Dipl\u00f4m\u00e9 en administration \u00e9conomique et sociale ainsi que management, Yannick, franco-allemand, a travaill\u00e9 douze ann\u00e9es...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/","og_locale":"pt_PT","og_type":"article","og_title":"Yannick RAUSCHER","og_url":"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2025-07-03T07:52:07+00:00","og_image":[{"width":1708,"height":2560,"url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/04\/Carlton_YR-scaled-e1713862361595.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/","url":"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/","name":"Yannick RAUSCHER - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/#primaryimage"},"image":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/04\/Carlton_YR-scaled-e1713862361595-1.jpg","datePublished":"2024-04-23T08:52:54+00:00","dateModified":"2025-07-03T07:52:07+00:00","description":"Dipl\u00f4m\u00e9 en administration \u00e9conomique et sociale ainsi que management, Yannick, franco-allemand, a travaill\u00e9 douze ann\u00e9es...","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/#primaryimage","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/04\/Carlton_YR-scaled-e1713862361595-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/04\/Carlton_YR-scaled-e1713862361595-1.jpg","width":694,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/pt-pt\/collaborateur\/yannick-rauscher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Yannick RAUSCHER"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/pt-pt\/#website","url":"https:\/\/www.carlton-international.com\/pt-pt\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/pt-pt\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/collaborateur\/3612122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/collaborateur"}],"about":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/types\/collaborateur"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/media\/4310160"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=3612122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}