{"id":4207946,"date":"2023-09-08T14:39:48","date_gmt":"2023-09-08T12:39:48","guid":{"rendered":"https:\/\/www.carlton-international.com\/annonce\/vence-sublime-sea-views-for-this-contemporary-5-bedroom-property\/"},"modified":"2026-05-04T00:10:48","modified_gmt":"2026-05-03T22:10:48","slug":"vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos","status":"publish","type":"annonce","link":"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/","title":{"rendered":"VENCE &#8211; VISTAS SUBLIMES SOBRE O MAR PARA ESTA PROPRIEDADE CONTEMPOR\u00c2NEA COM 5 QUARTOS"},"content":{"rendered":"<p>Situada no topo de uma colina, esta magn\u00edfica casa num terreno arborizado com cerca de 4 000 m2, concebida por um arquiteto de Vence, oferece vistas panor\u00e2micas deslumbrantes que se estendem de Saint-Jean-Cap-Ferrat at\u00e9 ao in\u00edcio de l&#8217;Est\u00e9rel, com vista para a pitoresca aldeia fortificada de Vence. Da piscina, \u00e9 poss\u00edvel contemplar a majestosa montanha Baou des Blancs.<\/p>\n<p>Com capacidade para 10 pessoas, esta propriedade com cerca de 400 m2 oferece no r\u00e9s do ch\u00e3o uma cozinha totalmente equipada, uma sala de estar cheia de luz e um luxuoso quarto principal. No andar de cima, quatro quartos elegantemente decorados oferecem conforto e privacidade aos seus h\u00f3spedes, cada um com a sua pr\u00f3pria casa de banho. Cada um dos quartos, embora diferentes, oferece uma vista igualmente apreci\u00e1vel e \u00fanica desta espl\u00eandida regi\u00e3o, e estende-se para o exterior para um terra\u00e7o ou acesso ao jardim.<\/p>\n<p>&#8212;<\/p>\n<p>Esta casa \u00e9 o local ideal para uma escapadela memor\u00e1vel, seja para relaxar junto \u00e0 piscina aquecida, explorar os arredores pitorescos ou simplesmente recarregar as baterias no cora\u00e7\u00e3o da natureza. O terra\u00e7o de 300 m\u00b2 oferece vistas deslumbrantes sobre o mar, acrescentando uma dimens\u00e3o ainda mais espetacular \u00e0 sua estadia. REF 918<\/p>\n<p>R\u00e9s do ch\u00e3o :<br \/>\n&#8211; Cozinha independente equipada<br \/>\n&#8211; Sala de estar\/jantar com vista panor\u00e2mica<br \/>\n&#8211; Casa de banho\/ WC de h\u00f3spedes<br \/>\n&#8211; Lavandaria (m\u00e1quina de lavar roupa, m\u00e1quina de secar roupa)<br \/>\n&#8211; Acesso interno \u00e0 garagem fechada<br \/>\n&#8211; Acesso ao terra\u00e7o com \u00e1rea de relaxamento e \u00e1rea de refei\u00e7\u00f5es ao ar livre<br \/>\n&#8211; Quarto #1 ensuite (cama de 180cm), quarto de vestir, casa de banho\/chuveiro, lavat\u00f3rio duplo, WC separado, televis\u00e3o, acesso ao terra\u00e7o, vista mar\/jardim<\/p>\n<p>1\u00ba andar:<br \/>\n&#8211; Uma \u00e1rea de escrit\u00f3rio com vista para a sala de estar, vista para o mar e para a montanha<br \/>\n&#8211; Quarto #2 ensuite (cama de 160cm), casa de banho com duche, lavat\u00f3rio duplo, sanita separada, quarto de vestir, televis\u00e3o, terra\u00e7o privado, vista mar\/montanha<br \/>\n&#8211; Quarto #3 ensuite (cama de 160cm), casa de banho com duche, lavat\u00f3rio duplo, WC separado, televis\u00e3o, varanda privada, vista para o jardim\/montanha<br \/>\n&#8211; Quarto #4 ensuite (cama 180cm), casa de banho com duche, lavat\u00f3rio duplo, sanita separada, televis\u00e3o, acesso ao jardim<br \/>\n&#8211; Quarto #5 ensuite (cama 160cm), casa de banho com duche, lavat\u00f3rio duplo, WC separado, quarto de vestir, televis\u00e3o, terra\u00e7o privado, vista mar\/montanha<\/p>\n<p>Comodidades adicionais: Alarme, videovigil\u00e2ncia, videofone, fibra \u00f3tica, dom\u00f3tica, ar condicionado revers\u00edvel, entrada fechada, garagem dupla, estacionamento exterior, persianas, piscina infinita aquecida (12m x 5m), sistema de rega autom\u00e1tica.<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","secteurs":[9293,3373,3373,9293,3372,3368,3449,1651],"service":[354,90,92,96,91,70,72,97,73,103,160,144,71,93,95,1384,94,88,101],"tags":[],"type_de_bien":[3407,8479],"type_annonce":[3410,3410],"class_list":{"0":"post-4207946","1":"annonce","2":"type-annonce","3":"status-publish","4":"hentry","5":"secteurs-alpes-maritimes-en-41","6":"secteurs-alpes-maritimes-pt-pt","9":"secteurs-france-pt-pt","10":"secteurs-france-en","11":"secteurs-vence-pt-pt","12":"secteurs-vence-en","13":"service-adoucisseur-deau","14":"service-air-conditionne","15":"service-alarme","16":"service-arrosage","17":"service-cloture","18":"service-domotique","19":"service-double-vitrage","20":"service-eclairage-exterieur","21":"service-fenetres-coulissantes","22":"service-fibre-optique","23":"service-internet","24":"service-meuble","25":"service-piscine","26":"service-portail-electrique","27":"service-stores-electriques","28":"service-triple-vitrage","29":"service-video-surveillance","30":"service-videophone","31":"service-volets-roulants-electriques","32":"type_de_bien-casa","33":"type_de_bien-maison-pt-pt","34":"type_annonce-aluguel-de-temporada"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>VENCE - VISTAS SUBLIMES SOBRE O MAR PARA ESTA PROPRIEDADE CONTEMPOR\u00c2NEA COM 5 QUARTOS - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VENCE - VISTAS SUBLIMES SOBRE O MAR PARA ESTA PROPRIEDADE CONTEMPOR\u00c2NEA COM 5 QUARTOS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-03T22:10:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/\",\"url\":\"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/\",\"name\":\"VENCE - VISTAS SUBLIMES SOBRE O MAR PARA ESTA PROPRIEDADE CONTEMPOR\u00c2NEA COM 5 QUARTOS - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#website\"},\"datePublished\":\"2023-09-08T12:39:48+00:00\",\"dateModified\":\"2026-05-03T22:10:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VENCE &#8211; VISTAS SUBLIMES SOBRE O MAR PARA ESTA PROPRIEDADE CONTEMPOR\u00c2NEA COM 5 QUARTOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/pt-pt\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"VENCE - VISTAS SUBLIMES SOBRE O MAR PARA ESTA PROPRIEDADE CONTEMPOR\u00c2NEA COM 5 QUARTOS - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/","og_locale":"pt_PT","og_type":"article","og_title":"VENCE - VISTAS SUBLIMES SOBRE O MAR PARA ESTA PROPRIEDADE CONTEMPOR\u00c2NEA COM 5 QUARTOS","og_url":"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-05-03T22:10:48+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/","url":"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/","name":"VENCE - VISTAS SUBLIMES SOBRE O MAR PARA ESTA PROPRIEDADE CONTEMPOR\u00c2NEA COM 5 QUARTOS - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/#website"},"datePublished":"2023-09-08T12:39:48+00:00","dateModified":"2026-05-03T22:10:48+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/vence-vistas-sublimes-sobre-o-mar-para-esta-propriedade-contemporanea-com-5-quartos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"VENCE &#8211; VISTAS SUBLIMES SOBRE O MAR PARA ESTA PROPRIEDADE CONTEMPOR\u00c2NEA COM 5 QUARTOS"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/pt-pt\/#website","url":"https:\/\/www.carlton-international.com\/pt-pt\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/pt-pt\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/annonce\/4207946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/types\/annonce"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=4207946"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/secteurs?post=4207946"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/service?post=4207946"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=4207946"},{"taxonomy":"type_de_bien","embeddable":true,"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/type_de_bien?post=4207946"},{"taxonomy":"type_annonce","embeddable":true,"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/type_annonce?post=4207946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}