{"id":4312110,"date":"2026-02-25T11:34:52","date_gmt":"2026-02-25T10:34:52","guid":{"rendered":"https:\/\/www.carlton-international.com\/?post_type=agence&#038;p=4312110"},"modified":"2026-03-10T11:46:46","modified_gmt":"2026-03-10T10:46:46","slug":"location","status":"publish","type":"agence","link":"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/","title":{"rendered":"Location"},"content":{"rendered":"<h3>As suas f\u00e9rias em Fran\u00e7a e no estrangeiro com a Carlton Rental<\/h3>\n<p style=\"text-align: justify;\">A Carlton Rental, sob a dire\u00e7\u00e3o de Alexandra Venard, \u00e9 a sua ag\u00eancia de <strong>arrendamento sazonal<\/strong> de prest\u00edgio em Fran\u00e7a e no estrangeiro. Descubra uma sele\u00e7\u00e3o <strong>exclusiva de propriedades de f\u00e9rias de luxo<\/strong> para estadias inesquec\u00edveis. Quer procure uma villa <strong>\u00e0 beira-mar<\/strong>, em Saint-Jean Cap Ferrat ou no <strong>Cap d&#8217;Antibes<\/strong>, um <strong>chal\u00e9 de montanha em Courchevel<\/strong> ou um <strong>apartamento prestigioso<\/strong> em Cannes, oferecemos-lhe op\u00e7\u00f5es de <strong>arrendamento de acordo com os seus desejos<\/strong>. Contacte-nos para f\u00e9rias memor\u00e1veis em fam\u00edlia ou entre amigos em <strong>destinos de sonho<\/strong>.<\/p>\n<p style=\"font-weight: 400;\"><strong>Sobre a Carlton International<\/strong><\/p>\n<p style=\"font-weight: 400;\">A Carlton International \u00e9 muito mais do que uma simples ag\u00eancia imobili\u00e1ria. Somos uma equipa dedicada de profissionais apaixonados pelo imobili\u00e1rio de alto padr\u00e3o. Com mais de 25 especialistas em imobili\u00e1rio, a nossa ag\u00eancia est\u00e1 idealmente posicionada para responder \u00e0s suas exig\u00eancias mais elevadas em mat\u00e9ria de compra, venda e arrendamento de im\u00f3veis de prest\u00edgio.<\/p>\n<p style=\"font-weight: 400;\"><strong>O nosso compromisso com a excel\u00eancia<\/strong><\/p>\n<p style=\"font-weight: 400;\">Na Carlton International, acreditamos na excel\u00eancia em tudo o que fazemos. Desde a primeira consulta at\u00e9 \u00e0 conclus\u00e3o da transa\u00e7\u00e3o, a nossa equipa compromete-se a fornecer um servi\u00e7o excecional a cada cliente. Compreendemos que cada propriedade \u00e9 \u00fanica, tal como cada cliente, por isso oferecemos um servi\u00e7o personalizado e \u00e0 medida para responder \u00e0s suas necessidades espec\u00edficas.<\/p>\n<p style=\"font-weight: 400;\"><strong>Uma sele\u00e7\u00e3o de im\u00f3veis exclusivos<\/strong><\/p>\n<p style=\"font-weight: 400;\">Quer procure uma villa \u00e0 beira-mar ou uma propriedade de luxo no interior, a Carlton International tem exatamente o que procura. O nosso portef\u00f3lio exclusivo \u00e9 cuidadosamente selecionado para oferecer as melhores op\u00e7\u00f5es dispon\u00edveis no mercado.<\/p>\n<p style=\"font-weight: 400;\"><strong>Contacte-nos<\/strong><\/p>\n<p style=\"font-weight: 400;\">Contacte-nos hoje mesmo para concretizar os seus projetos imobili\u00e1rios.<\/p>\n","protected":false},"featured_media":4302346,"menu_order":0,"template":"","secteurs":[],"class_list":["post-4312110","agence","type-agence","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Location - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Location\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T10:46:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/1eefdaaad9976cd0c9de8ba28a7d47f9_90d27fa936_1920-original-3710802-45.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1623\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/\",\"url\":\"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/\",\"name\":\"Location - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/1eefdaaad9976cd0c9de8ba28a7d47f9_90d27fa936_1920-original-3710802-45.jpg\",\"datePublished\":\"2026-02-25T10:34:52+00:00\",\"dateModified\":\"2026-03-10T10:46:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/#primaryimage\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/1eefdaaad9976cd0c9de8ba28a7d47f9_90d27fa936_1920-original-3710802-45.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/1eefdaaad9976cd0c9de8ba28a7d47f9_90d27fa936_1920-original-3710802-45.jpg\",\"width\":1623,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Location\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/pt-pt\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Location - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/","og_locale":"pt_PT","og_type":"article","og_title":"Location","og_url":"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-03-10T10:46:46+00:00","og_image":[{"width":1623,"height":1080,"url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/1eefdaaad9976cd0c9de8ba28a7d47f9_90d27fa936_1920-original-3710802-45.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/","url":"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/","name":"Location - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/#primaryimage"},"image":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/1eefdaaad9976cd0c9de8ba28a7d47f9_90d27fa936_1920-original-3710802-45.jpg","datePublished":"2026-02-25T10:34:52+00:00","dateModified":"2026-03-10T10:46:46+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/#primaryimage","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/1eefdaaad9976cd0c9de8ba28a7d47f9_90d27fa936_1920-original-3710802-45.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/1eefdaaad9976cd0c9de8ba28a7d47f9_90d27fa936_1920-original-3710802-45.jpg","width":1623,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/pt-pt\/agence\/location\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Location"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/pt-pt\/#website","url":"https:\/\/www.carlton-international.com\/pt-pt\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/pt-pt\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/agence\/4312110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/agence"}],"about":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/types\/agence"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/media\/4302346"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=4312110"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/pt-pt\/wp-json\/wp\/v2\/secteurs?post=4312110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}