{"id":3502196,"date":"2025-05-21T12:16:09","date_gmt":"2025-05-21T10:16:09","guid":{"rendered":"https:\/\/www.carlton-international.com\/compra\/nice-environs\/falicon\/"},"modified":"2026-03-18T11:25:21","modified_gmt":"2026-03-18T10:25:21","slug":"falicon","status":"publish","type":"page","link":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/","title":{"rendered":"Falicon"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3502196\" class=\"elementor elementor-3502196 elementor-3329085\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a9634d contentpd30 e-flex e-con-boxed e-con e-parent\" data-id=\"7a9634d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div data-dce-title-color=\"#BFA473\" class=\"elementor-element elementor-element-eb0326c elementor-widget elementor-widget-heading\" data-id=\"eb0326c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Falicon<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-792e6aa7 contentpd20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"792e6aa7\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ab2cffd\" data-id=\"4ab2cffd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f80d67 elementor-widget elementor-widget-shortcode\" data-id=\"3f80d67\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">    <div class=\"ci-dis-ads_wrapper\" data-id-page=\"3502196\" id=\"ci-ads-results\">\n                <!-- TOTAL RESULTS -->\n        <div class=\"ci-dis-ads_total_results aa\">\n            <div class=\"ci-dis-description_contact_results a2345 3502196\">\n            \n                <p>\n                <a href=\"https:\/\/www.carlton-international.com\/es\/compra\/\">compra<\/a> &gt; <a href=\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/\">nice &#038; environs<\/a> &gt; <a href=\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/\">falicon<\/a> &gt; <span data-id=\"3502196\">1 r\u00e9sultat<\/span>                <\/p>\n                            <\/div>\n        <\/div>\n                    <!-- HEADER -->\n            <div class=\"ci-dis-ads_header\">\n                <!-- PAGINATION -->\n                <div class=\"ci-dis-ads_pagination\">\n                                    <\/div>\n                <!-- SORT -->\n\n                                    <div class=\"ci-dis-ads_sort\">\n                                                    <select class=\"ci-dis-ads_price-filter\" name=\"ci-dis-ads_price-filter\" id=\"ci-dis-ads_price-filter\">\n                                <option value=\"\">Ordenar por precio<\/option>\n                                <option value=\"low_to_hight\"> &#8593 Precio ascendente<\/option>\n                                <option value=\"hight_to_low\"> &#8595 Precio descendente<\/option>\n                            <\/select>\n                                            <\/div>\n                    <!-- DISPLAY -->\n                    <div class=\"ci-dis-ads_disp\">\n                                                    <button class=\"ci-dis-ads_btn-filter \" data-display=\"list\">Lista<\/button>\n                            <button class=\"ci-dis-ads_btn-filter ci-dis-ads_btn-active\" data-display=\"grid\">Mosaico<\/button>\n                                            <\/div>\n                            <\/div>\n                <!-- CONTENT -->\n        <div class=\"ci-dis-ads_content ci-disp-grid\">\n            <div class=\"ci-sdia_ad-item \" data-title=\"Haven of peace, near Nice, villa with swimming pool\" data-ref=\"13789\">\n    <div class=\"cifi-item cifi-item_compact cifi-empty\"\n    id=\"cifi-item-82872082\"\n    data-id=\"82872082\"\n    data-title=\"Havre de paix, proche de Nice, villa avec piscine\"\n    data-titleen=\"Haven of peace, near Nice, villa with swimming pool\"\n    data-titlept=\"Haven of peace, near Nice, villa with swimming pool\"\n    data-titlede=\"Oase der Ruhe in der N\u00e4he von Nizza\"\n    data-titlees=\"Haven of peace, near Nice, villa with swimming pool\"\n    data-url=\"https:\/\/www.carlton-international.com\/annonce\/havre-de-paix-proche-de-nice-villa-avec-piscine\/\"\n    data-urlen=\"https:\/\/www.carlton-international.com\/en\/annonce\/haven-of-peace-near-nice-villa-with-swimming-pool\/\"\n    data-urlpt=\"https:\/\/www.carlton-international.com\/pt-pt\/annonce\/haven-of-peace-near-nice-villa-with-swimming-pool\/\"\n    data-urlde=\"https:\/\/www.carlton-international.com\/de\/annonce\/oase-der-ruhe-in-der-naehe-von-nizza\/\"\n    data-urles=\"https:\/\/www.carlton-international.com\/es\/annonce\/haven-of-peace-near-nice-villa-with-swimming-pool\/\"\n    data-thumb=\"https:\/\/media.apimo.pro\/cache\/05ea4104df1c47c7686414505bc893a6_29b900e5df_1920-original.jpg\"\n    data-city=\"Falicon\"\n    data-surface=\"128 m\u00b2\"\n    data-stats=\"Terrain: 1825 m\u00b2 | 4 pi\u00e8ces | 3 chambres\"\n    data-statsen=\"Land: 1825 m\u00b2 | 4 rooms | 3 bedrooms\"\n    data-statspt=\"Terreno: 1825 m\u00b2 | 4 divis\u00f5es | 3 quartos\"\n    data-statsde=\"Grundst\u00fcck: 1825 m\u00b2 | 4 Zimmer | 3 Schlafzimmer\"\n    data-statses=\"Terreno: 1825 m\u00b2 | 4 habitaciones | 3 dormitorios\"\n    data-price=\"1.090.000 \u20ac\"\n    data-priceen=\"\u20ac1.090.000\"\n    data-pricept=\"\u20ac1.090.000\"\n    data-pricede=\"\u20ac1.090.000\"\n    data-pricees=\"\u20ac1.090.000\">\n    <a href=\"javascript:void(0);\" class=\"cifi_btn\">\n        <span class=\"cifi_btn-icon\"><\/span>\n        <span class=\"cifi_btn-text\">Add to favorite<\/span>\n    <\/a>\n<\/div>\n    <div class=\"ci-sdia_ad-item_img ab\">\n        \n        \n                                    <div class=\"slick-inner-sdia_ad-item\">\n                                                <div class=\"slide-sdia_ad-item\">\n                                <a href=\"https:\/\/www.carlton-international.com\/es\/annonce\/haven-of-peace-near-nice-villa-with-swimming-pool\/\">\n                                    <img decoding=\"async\" \n                                        loading=\"lazy\"\n                                        src=\"https:\/\/media.apimo.pro\/cache\/05ea4104df1c47c7686414505bc893a6_29b900e5df_1920-original.jpg\" \n                                        alt=\"\"\n                                    \/>\n                                    <p class=\"title-slide-sdia_ad-item \">Descubrir la propiedad<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"slide-sdia_ad-item\">\n                                <a href=\"https:\/\/www.carlton-international.com\/es\/annonce\/haven-of-peace-near-nice-villa-with-swimming-pool\/\">\n                                    <img decoding=\"async\" \n                                        loading=\"lazy\"\n                                        src=\"https:\/\/media.apimo.pro\/cache\/faa20c7e9793f9fd64a0f7412b50c424_6c02fb529d_1920-original.jpg\" \n                                        alt=\"\"\n                                    \/>\n                                    <p class=\"title-slide-sdia_ad-item \">Descubrir la propiedad<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"slide-sdia_ad-item\">\n                                <a href=\"https:\/\/www.carlton-international.com\/es\/annonce\/haven-of-peace-near-nice-villa-with-swimming-pool\/\">\n                                    <img decoding=\"async\" \n                                        loading=\"lazy\"\n                                        src=\"https:\/\/media.apimo.pro\/cache\/353be7a8fa015a05bcd81bc2dc981297_c7882dcd2b_1920-original.jpg\" \n                                        alt=\"\"\n                                    \/>\n                                    <p class=\"title-slide-sdia_ad-item \">Descubrir la propiedad<\/p>\n                                <\/a>\n                            <\/div>\n                                        <\/div>\n                        <\/div>\n    <div class=\"ci-sdia_ad-item_datas\">\n        <div class=\"ci-sdia_ad-item_metas\">\n                            <a class=\"ci-sdia_ad-item_title\" href=\"https:\/\/www.carlton-international.com\/es\/annonce\/haven-of-peace-near-nice-villa-with-swimming-pool\/\">Falicon <\/a>\n                        <div class=\"ci-sdia_ad-item_metas-wrap\">\n                <div class=\"ci-sdia_ad-item_metas-loc\"><div>Francia<\/div><\/div>                                    <div class=\"ci-sdia_ad-item_metas-map\">\n                        <a target=\"_blank\" class=\"ci-sdia_ad-item_btn-icon ci-sdia_ad-item_btn-icon_map\"><span class=\"ci-sdia_hide\">Map<\/span><\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n        <div class=\"ci-sdia_ad-item_stats \">3 dormitorios | <span class=\"ci-surface\">128 m\u00b2<\/span> | 4 habitaciones<\/div>\n        <div class=\"ci-sdia_ad-item_comp\">\n            <div class=\"ci-sdia_ad-item_footer-ref\">\n                <span><strong>Ref.<\/strong> 13789<\/span>\n            <\/div>\n            <div class=\"wrap-item-price\">\n                                                                                        <div class=\"ci-sdia_ad-item_price ci-price\" data-7 data-price=\"1090000\">\u20ac1.090.000<\/div>\n                                                                                        <\/div>\n\n        <\/div>\n\n                                                        <div class=\"popup_contact_bien_div\"><\/div>\n                                    \n        <div class=\"ci-sdia_ad-item_footer-wrap\">\n            <p class=\"ci-sdia_ad-item_footer\"><a href=\"https:\/\/www.carlton-international.com\/es\/annonce\/haven-of-peace-near-nice-villa-with-swimming-pool\/\">Ver detalles<\/a><\/p>\n            <div class=\"ci-sdia_ad-item_footer-btns\">\n                <a href=\"tel:\" class=\"ci-sdia_ad-item_footer-btn ci-sdia_ad-item_btn-icon ci-sdia_ad-item_btn-icon_phone\"><span class=\"ci-sdia_hide\">Phone<\/span><\/a>\n                <a href=\"javascript:;\" data-unique-id=\"82872082\" data-properties-id=\"31847303\" data-email=\"\" class=\"ci-sdia_ad-item_footer-btn ci-sdia_ad-item_btn-icon ci-sdia_ad-item_btn-icon_mail popup_contact_bien\"><span class=\"ci-sdia_hide\">Email<\/span><\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n        <\/div>\n        <!-- FOOTER -->\n        <div class=\"ci-dis-ads_footer\">\n            <!-- PAGINATION -->\n            <div class=\"ci-dis-ads_pagination\">\n                            <\/div>\n        <\/div>\n                 <\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fb9e81 description elementor-widget elementor-widget-text-editor\" data-id=\"7fb9e81\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 22px\">COMPRA, VENTA Y ALQUILER DE PROPIEDADES DE PRESTIGIO EN LA COSTA AZUL Y A NIVEL INTERNACIONAL<\/h2>\n<p><strong>\u00bfDesea comprar, vender o alquilar una propiedad de prestigio y busca un socio de confianza que le acompa\u00f1e en su proyecto inmobiliario?<\/strong><\/p>\n<p>Desde hace m\u00e1s de 30 a\u00f1os, Carlton International encarna la excelencia en el sector inmobiliario de lujo, acompa\u00f1ando a una clientela internacional en la compra, venta y alquiler de propiedades excepcionales en la Costa Azul y a nivel internacional.<br \/>\nGracias a nuestra reconocida experiencia y a nuestra red internacional, le ofrecemos un acompa\u00f1amiento personalizado, confidencial y a medida para hacer realidad sus proyectos inmobiliarios m\u00e1s ambiciosos.<\/p>\n<p><strong>Una selecci\u00f3n exclusiva de propiedades de lujo<\/strong><br \/>\nCarlton International le ofrece una selecci\u00f3n rigurosa de propiedades de prestigio, que incluye villas contempor\u00e1neas, apartamentos de alta gama, propiedades privadas y residencias excepcionales situadas en los destinos m\u00e1s solicitados.<\/p>\n<p>Nuestro portafolio inmobiliario incluye:<br \/>\n\u2022 Villas de lujo con vistas al mar<br \/>\n\u2022 Propiedades excepcionales frente al mar<br \/>\n\u2022 Apartamentos de alto standing en ubicaciones premium<br \/>\n\u2022 Fincas con encanto en el coraz\u00f3n de paisajes mediterr\u00e1neos<br \/>\n\u2022 Residencias exclusivas que ofrecen privacidad y serenidad<br \/>\nCada propiedad se selecciona cuidadosamente por su ubicaci\u00f3n, arquitectura y car\u00e1cter \u00fanico para satisfacer las expectativas de una clientela exigente.<\/p>\n<p><strong>30 a\u00f1os de excelencia y experiencia inmobiliaria<\/strong><br \/>\nDesde hace m\u00e1s de tres d\u00e9cadas, Carlton International acompa\u00f1a a compradores, vendedores y propietarios en sus proyectos inmobiliarios de prestigio.<\/p>\n<p>Nuestra reputaci\u00f3n se basa en:<br \/>\n\u2022 Una profunda experiencia en el mercado inmobiliario de lujo<br \/>\n\u2022 Una red internacional de compradores, inversores e inquilinos<br \/>\n\u2022 Un acompa\u00f1amiento a medida en cada etapa<br \/>\n\u2022 Un conocimiento detallado de los mercados locales e internacionales<br \/>\nYa sea que desee adquirir una propiedad excepcional, vender su propiedad en las mejores condiciones o alquilar una residencia de prestigio, nuestros equipos de expertos hacen todo lo posible para valorizar su proyecto.<\/p>\n<p>\u2022 alquiler villa Cannes Festival<br \/>\n\u2022 inmobiliaria de lujo Costa Azul<br \/>\nEsta optimizaci\u00f3n puede aumentar significativamente el tr\u00e1fico internacional hacia su sitio web.<\/p>\n<p><strong>Alquiler de villas, apartamentos y chalets de lujo<\/strong><br \/>\nCarlton International tambi\u00e9n ofrece una selecci\u00f3n exclusiva de alquileres de alta gama para estancias excepcionales en los destinos m\u00e1s demandados.<br \/>\nEn la Costa Azul, ofrecemos alquileres de prestigio que incluyen:<br \/>\n\u2022 Villas de lujo con piscina y vistas al mar<br \/>\n\u2022 Propiedades privadas en urbanizaciones seguras<br \/>\n\u2022 Apartamentos de alta gama en el centro de la ciudad o frente al mar<br \/>\n\u2022 Residencias excepcionales cerca de playas, puertos y campos de golf<br \/>\nNuestros equipos tambi\u00e9n ofrecen alquileres de chalets de lujo en las mejores estaciones de esqu\u00ed, permiti\u00e9ndole disfrutar de una estancia exclusiva en la monta\u00f1a en un entorno excepcional.<br \/>\nYa sea para vacaciones en familia, una estancia con amigos o un evento privado, nuestras propiedades ofrecen confort, elegancia y servicios premium.<\/p>\n<p><strong>Alquileres durante congresos y festivales en Cannes<\/strong><br \/>\nGracias a su presencia hist\u00f3rica en la Costa Azul, Carlton International tambi\u00e9n acompa\u00f1a a sus clientes durante los grandes eventos internacionales organizados en Cannes.<br \/>\nOfrecemos alquileres de apartamentos y villas de prestigio durante los principales congresos y festivales, como:<br \/>\n\u2022 Festival de Cannes<br \/>\n\u2022 MIPIM<br \/>\n\u2022 Cannes Lions<br \/>\n\u2022 MIPCOM<br \/>\n\u2022 Cannes Yachting Festival<br \/>\n\u2022 Numerosos congresos y eventos profesionales en el Palais des Festivals<br \/>\nNuestras propiedades ubicadas cerca del centro de la ciudad, La Croisette y el Palais des Festivals permiten a profesionales y empresas beneficiarse de alojamientos de alto nivel perfectamente adaptados a sus necesidades.<\/p>\n<p><strong>Acompa\u00f1amiento a medida para su estancia<\/strong><br \/>\nAlquilar una propiedad con Carlton International significa beneficiarse de un servicio personalizado y de un acompa\u00f1amiento de alto nivel para ofrecerle una experiencia \u00fanica.<br \/>\nNuestros equipos le acompa\u00f1an en la organizaci\u00f3n de su estancia y tambi\u00e9n pueden ofrecer servicios exclusivos:<br \/>\n\u2022 Organizaci\u00f3n de estancias a medida<br \/>\n\u2022 Recepci\u00f3n personalizada en su propiedad<br \/>\n\u2022 Servicio de conserjer\u00eda privada<br \/>\n\u2022 Traslados, ch\u00f3feres y servicios VIP<br \/>\n\u2022 Organizaci\u00f3n de eventos o estancias profesionales<br \/>\nNuestro objetivo es ofrecerle una experiencia de estancia excepcional en las propiedades m\u00e1s hermosas.<\/p>\n<p>Con Carlton International, descubra un enfoque \u00fanico del inmobiliario de prestigio basado en la excelencia, la experiencia y m\u00e1s de 30 a\u00f1os de trayectoria al servicio de su proyecto.<\/p>\n<p><strong>Nuestras \u00e1reas de especializaci\u00f3n en la Costa Azul<\/strong><br \/>\nNuestras agencias est\u00e1n ubicadas en las zonas m\u00e1s prestigiosas de la regi\u00f3n:<br \/>\nAntibes \/ Cap d\u2019Antibes &amp; Juan-les-Pins<br \/>\nInterior de Cannes<br \/>\nInterior del Var<br \/>\nCannes y alrededores<br \/>\nFr\u00e9jus y Saint-Rapha\u00ebl<br \/>\nMougins y alrededores<br \/>\nNiza y alrededores<br \/>\nCerca de M\u00f3naco<br \/>\nSaint-Paul-de-Vence y alrededores<br \/>\nSaint-Tropez y alrededores<br \/>\nValbonne y alrededores<br \/>\nGracias a nuestra presencia local y nuestra red internacional, ofrecemos las mejores oportunidades inmobiliarias en la Costa Azul.<\/p>\n<p><strong>Experiencia internacional<\/strong><br \/>\nM\u00e1s all\u00e1 de la Costa Azul, Carlton International tambi\u00e9n acompa\u00f1a a sus clientes en sus proyectos inmobiliarios en varios destinos europeos demandados.<br \/>\nNuestros equipos cuentan con una experiencia reconocida en mercados internacionales, especialmente:<br \/>\n\u2022 En Alsacia, una regi\u00f3n con un patrimonio arquitect\u00f3nico \u00fanico<br \/>\n\u2022 En Baden-Baden, Alemania, un destino prestigioso reconocido por su calidad de vida y propiedades con car\u00e1cter<br \/>\n\u2022 En la Costa del Sol, uno de los mercados inmobiliarios m\u00e1s din\u00e1micos de Europa<br \/>\nOfrecemos especialmente propiedades de lujo en las zonas de Marbella y Estepona, dos destinos emblem\u00e1ticos del Mediterr\u00e1neo que ofrecen un estilo de vida excepcional entre mar, golf y arte de vivir.<\/p>\n<p><strong>Acompa\u00f1amiento a medida para comprar, vender o alquilar<\/strong><br \/>\nEn Carlton International, cada proyecto inmobiliario merece una atenci\u00f3n especial. Nuestros equipos de expertos en inmobiliario de prestigio le acompa\u00f1an con profesionalidad y discreci\u00f3n en cada etapa:<br \/>\n\u2022 Valoraci\u00f3n y puesta en valor de su propiedad<br \/>\n\u2022 Estrategia de comercializaci\u00f3n internacional<br \/>\n\u2022 B\u00fasqueda personalizada de propiedades de lujo<br \/>\n\u2022 Organizaci\u00f3n de visitas privadas<br \/>\n\u2022 Acompa\u00f1amiento jur\u00eddico y administrativo<br \/>\n\u2022 Gesti\u00f3n y alquiler de propiedades de prestigio<br \/>\nNuestro objetivo es ofrecerle una experiencia inmobiliaria fluida, segura y perfectamente adaptada a sus expectativas.<\/p>\n<p><strong>Su proyecto inmobiliario comienza aqu\u00ed<\/strong><br \/>\nYa sea que desee comprar una villa de lujo, vender una propiedad de prestigio, alquilar una residencia excepcional o invertir en el sector inmobiliario de alta gama, los equipos de Carlton International est\u00e1n a su disposici\u00f3n.<\/p>\n<p>Contacte con la agencia Carlton International de su elecci\u00f3n para beneficiarse del acompa\u00f1amiento de nuestros expertos: <a href=\"https:\/\/www.carlton-international.com\/es\/contactenos\/\">https:\/\/www.carlton-international.com\/es\/contactenos\/<\/a><\/p>\n<p>Con Carlton International, descubra un enfoque \u00fanico del inmobiliario de prestigio basado en la excelencia, la experiencia y m\u00e1s de 30 a\u00f1os de trayectoria al servicio de su proyecto.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Falicon<\/p>\n","protected":false},"author":9,"featured_media":2457565,"parent":2457540,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"class_list":["post-3502196","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Propri\u00e9t\u00e9s \u00e0 vendre Arri\u00e8re-pays Cannois. Carlton International<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre s\u00e9lection de propri\u00e9t\u00e9s de luxe \u00e0 vendre dans l&#039;arri\u00e8re-pays cannois et profitez de la tranquillit\u00e9 de cette r\u00e9gion pris\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Falicon\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre s\u00e9lection de propri\u00e9t\u00e9s de luxe \u00e0 vendre dans l&#039;arri\u00e8re-pays cannois et profitez de la tranquillit\u00e9 de cette r\u00e9gion pris\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-18T10:25:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"649\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/\",\"url\":\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/\",\"name\":\"Propri\u00e9t\u00e9s \u00e0 vendre Arri\u00e8re-pays Cannois. Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg\",\"datePublished\":\"2025-05-21T10:16:09+00:00\",\"dateModified\":\"2026-03-18T10:25:21+00:00\",\"description\":\"D\u00e9couvrez notre s\u00e9lection de propri\u00e9t\u00e9s de luxe \u00e0 vendre dans l'arri\u00e8re-pays cannois et profitez de la tranquillit\u00e9 de cette r\u00e9gion pris\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/#primaryimage\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg\",\"width\":649,\"height\":487,\"caption\":\"Luxury Villas In Cannes Countryside\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compra\",\"item\":\"https:\/\/www.carlton-international.com\/es\/compra\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nice &#038; Environs\",\"item\":\"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Falicon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/es\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Propri\u00e9t\u00e9s \u00e0 vendre Arri\u00e8re-pays Cannois. Carlton International","description":"D\u00e9couvrez notre s\u00e9lection de propri\u00e9t\u00e9s de luxe \u00e0 vendre dans l'arri\u00e8re-pays cannois et profitez de la tranquillit\u00e9 de cette r\u00e9gion pris\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/","og_locale":"es_ES","og_type":"article","og_title":"Falicon","og_description":"D\u00e9couvrez notre s\u00e9lection de propri\u00e9t\u00e9s de luxe \u00e0 vendre dans l'arri\u00e8re-pays cannois et profitez de la tranquillit\u00e9 de cette r\u00e9gion pris\u00e9e.","og_url":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-03-18T10:25:21+00:00","og_image":[{"width":649,"height":487,"url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/","url":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/","name":"Propri\u00e9t\u00e9s \u00e0 vendre Arri\u00e8re-pays Cannois. Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/#primaryimage"},"image":{"@id":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg","datePublished":"2025-05-21T10:16:09+00:00","dateModified":"2026-03-18T10:25:21+00:00","description":"D\u00e9couvrez notre s\u00e9lection de propri\u00e9t\u00e9s de luxe \u00e0 vendre dans l'arri\u00e8re-pays cannois et profitez de la tranquillit\u00e9 de cette r\u00e9gion pris\u00e9e.","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/#primaryimage","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg","width":649,"height":487,"caption":"Luxury Villas In Cannes Countryside"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/falicon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/es\/"},{"@type":"ListItem","position":2,"name":"Compra","item":"https:\/\/www.carlton-international.com\/es\/compra\/"},{"@type":"ListItem","position":3,"name":"Nice &#038; Environs","item":"https:\/\/www.carlton-international.com\/es\/compra\/nice-environs\/"},{"@type":"ListItem","position":4,"name":"Falicon"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/es\/#website","url":"https:\/\/www.carlton-international.com\/es\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/es\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/es\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/pages\/3502196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/comments?post=3502196"}],"version-history":[{"count":2,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/pages\/3502196\/revisions"}],"predecessor-version":[{"id":4315809,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/pages\/3502196\/revisions\/4315809"}],"up":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/pages\/2457540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/media\/2457565"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/media?parent=3502196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}