{"id":2332830,"date":"2024-05-16T16:15:07","date_gmt":"2024-05-16T14:15:07","guid":{"rendered":"https:\/\/www.carlton-international.com\/buying-dream-homes-and-investment-opportunities-on-the-french-riviera\/alsace\/"},"modified":"2026-03-30T03:44:03","modified_gmt":"2026-03-30T01:44:03","slug":"alsace","status":"publish","type":"page","link":"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/","title":{"rendered":"Alsace"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2332830\" class=\"elementor elementor-2332830 elementor-1667472\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a9634d contentpd20 e-flex e-con-boxed e-con e-parent\" data-id=\"7a9634d\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb0326c elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"eb0326c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Alsace<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-792e6aa7 contentpd20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"792e6aa7\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ab2cffd\" data-id=\"4ab2cffd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f80d67 elementor-widget elementor-widget-shortcode\" data-id=\"3f80d67\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">    <div class=\"ci-dis-ads_wrapper\" data-id-page=\"2332830\" id=\"ci-ads-results\">\n                <!-- TOTAL RESULTS -->\n        <div class=\"ci-dis-ads_total_results aa\">\n            <div class=\"ci-dis-description_contact_results a2345 2332830\">\n            \n                <p>\n                <a href=\"https:\/\/www.carlton-international.com\/es\/compra\/\">compra<\/a> &gt; <a href=\"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/\">alsace<\/a> &gt; <span data-id=\"2332830\">0 r\u00e9sultat<\/span>                <\/p>\n                            <\/div>\n        <\/div>\n                    <!-- HEADER -->\n            <div class=\"ci-dis-ads_header\">\n                <!-- PAGINATION -->\n                <div class=\"ci-dis-ads_pagination\">\n                                    <\/div>\n                <!-- SORT -->\n\n                                    <div class=\"ci-dis-ads_sort\">\n                                            <\/div>\n                    <!-- DISPLAY -->\n                    <div class=\"ci-dis-ads_disp\">\n                                            <\/div>\n                            <\/div>\n                <!-- CONTENT -->\n        <div class=\"ci-dis-ads_content ci-disp-grid\">\n                                                                    <div class=\"ci-dis-ads_content-empty s1\" style=\"display: flex;\">\n                                        <p class=\"ci-dis-ads_content-empty_text\"><\/p>\n                                        <div><div>\n<div>Numerosas propiedades que coinciden con su b\u00fasqueda se comercializan de manera <strong>estrictamente confidencial, en formato offmarket, directamente por nuestros equipos.<\/strong><\/div>\n<div>Le invitamos a <strong>contactar con la agencia Carlton International correspondiente a la direcci\u00f3n buscada<\/strong> para acceder a estas oportunidades exclusivas :\u00a0<a href=\"https:\/\/www.carlton-international.com\/es\/contactenos\/\">https:\/\/www.carlton-international.com\/es\/contactenos\/<\/a><\/div>\n<\/div>\n<\/div>\n                                    <\/div>\n                                                            \n                                                <\/div>\n        <!-- FOOTER -->\n        <div class=\"ci-dis-ads_footer\">\n            <!-- PAGINATION -->\n            <div class=\"ci-dis-ads_pagination\">\n                            <\/div>\n        <\/div>\n                 <\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":2332567,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"class_list":["post-2332830","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alsace - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alsace\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T01:44:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/\",\"url\":\"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/\",\"name\":\"Alsace - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#website\"},\"datePublished\":\"2024-05-16T14:15:07+00:00\",\"dateModified\":\"2026-03-30T01:44:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compra\",\"item\":\"https:\/\/www.carlton-international.com\/es\/compra\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alsace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/es\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alsace - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/","og_locale":"es_ES","og_type":"article","og_title":"Alsace","og_url":"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-03-30T01:44:03+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/","url":"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/","name":"Alsace - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/es\/#website"},"datePublished":"2024-05-16T14:15:07+00:00","dateModified":"2026-03-30T01:44:03+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/es\/compra\/alsace\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/es\/compra\/alsace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/es\/"},{"@type":"ListItem","position":2,"name":"Compra","item":"https:\/\/www.carlton-international.com\/es\/compra\/"},{"@type":"ListItem","position":3,"name":"Alsace"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/es\/#website","url":"https:\/\/www.carlton-international.com\/es\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/es\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/es\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/pages\/2332830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/comments?post=2332830"}],"version-history":[{"count":4,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/pages\/2332830\/revisions"}],"predecessor-version":[{"id":31845749,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/pages\/2332830\/revisions\/31845749"}],"up":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/pages\/2332567"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/media?parent=2332830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}