{"id":4302000,"date":"2024-06-12T17:37:55","date_gmt":"2024-06-12T15:37:55","guid":{"rendered":"https:\/\/www.carlton-international.com\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/"},"modified":"2026-04-21T00:10:58","modified_gmt":"2026-04-20T22:10:58","slug":"encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4","status":"publish","type":"annonce","link":"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/","title":{"rendered":"Encantadora villa de 6 dormitorios en las colinas de \u00c8ze"},"content":{"rendered":"<p>Encantadora villa de 280 m\u00b2 situada en las colinas de \u00c8ze, con vistas al mar y al pueblo. La propiedad consta de una casa principal y tres apartamentos independientes, cada uno con una sala de estar con cocina totalmente equipada y un dormitorio con cuarto de ba\u00f1o con ducha y WC, con capacidad para 12 personas.<br \/>\nUna piscina climatizada completa el confort de esta encantadora residencia.<br \/>\nREF. 1026<\/p>\n<p>&#8212;<br \/>\nCasa principal<\/p>\n<p>Planta baja:<\/p>\n<p>&#8211; Entrada,<br \/>\n&#8211; Aseo de invitados,<br \/>\n&#8211; Cocina americana totalmente equipada,<br \/>\n&#8211; Sal\u00f3n-comedor abierto a una bonita terraza con acceso a la piscina y su comedor exterior, vistas a las colinas y al mar,<br \/>\n&#8211; Dormitorio 1: cama doble 140&#215;200 con cuarto de ba\u00f1o con ducha y WC<\/p>\n<p>Primera planta:<br \/>\n&#8211; Dormitorio 2: dormitorio principal, cama doble 160&#215;200 con acceso a dos balcones, cuarto de ba\u00f1o con ducha y WC,<br \/>\n&#8211; Dormitorio 3: cama doble de 140&#215;200 con cuarto de ba\u00f1o con ducha y WC.<\/p>\n<p>Casa de hu\u00e9spedes<\/p>\n<p>&#8211; Piso 1: sal\u00f3n, cocina equipada, dormitorio con cama doble 140&#215;200 y cuarto de ducha con WC<\/p>\n<p>&#8211; Apartamento 2: Sal\u00f3n, cocina equipada, dormitorio con cama de matrimonio 140&#215;200 y cuarto de ducha con WC<\/p>\n<p>-Piso 3: Sal\u00f3n, cocina equipada, dormitorio con cama de matrimonio (140&#215;200) y cuarto de ducha con WC.<\/p>\n<p>Piscina climatizada con cloro (5&#215;10)<\/p>\n<p>Servicios adicionales: 2 plazas de aparcamiento, fibra hasta los pisos independientes, aire acondicionado, barbacoa.<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","secteurs":[9298,9298,5867,5867,1680,5932,3368,5866],"service":[90,92,103,160,71],"tags":[7905,7896,7897,7895,138,89,2239,4545,78,4546,4550],"type_de_bien":[5860,5860],"type_annonce":[5878,5878],"class_list":{"0":"post-4302000","1":"annonce","2":"type-annonce","3":"status-publish","4":"hentry","5":"secteurs-alpes-maritimes-en-13","7":"secteurs-alpes-maritimes-es","9":"secteurs-eze-en","10":"secteurs-eze-es","11":"secteurs-france-en","12":"secteurs-france-es","13":"service-air-conditionne","14":"service-alarme","15":"service-fibre-optique","16":"service-internet","17":"service-piscine","18":"tags-appartement-ou-maison-dinvites","19":"tags-diagnostiques-techniques","20":"tags-passeport-id","21":"tags-site-carlton-international","22":"tags-chambre-staff","23":"tags-mer","24":"tags-piscine-chauffee","25":"tags-plateformes","26":"tags-quartier-residentiel","27":"tags-reseaux-sociaux","28":"tags-titre-de-propriete","29":"type_de_bien-hogar","31":"type_annonce-alquiler-por-temporada"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Encantadora villa de 6 dormitorios en las colinas de \u00c8ze - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encantadora villa de 6 dormitorios en las colinas de \u00c8ze\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T22:10:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/\",\"url\":\"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/\",\"name\":\"Encantadora villa de 6 dormitorios en las colinas de \u00c8ze - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#website\"},\"datePublished\":\"2024-06-12T15:37:55+00:00\",\"dateModified\":\"2026-04-20T22:10:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encantadora villa de 6 dormitorios en las colinas de \u00c8ze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/es\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Encantadora villa de 6 dormitorios en las colinas de \u00c8ze - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/","og_locale":"es_ES","og_type":"article","og_title":"Encantadora villa de 6 dormitorios en las colinas de \u00c8ze","og_url":"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-04-20T22:10:58+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/","url":"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/","name":"Encantadora villa de 6 dormitorios en las colinas de \u00c8ze - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/es\/#website"},"datePublished":"2024-06-12T15:37:55+00:00","dateModified":"2026-04-20T22:10:58+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/es\/annonce\/encantadora-villa-de-6-dormitorios-en-las-colinas-de-eze-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/es\/"},{"@type":"ListItem","position":2,"name":"Encantadora villa de 6 dormitorios en las colinas de \u00c8ze"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/es\/#website","url":"https:\/\/www.carlton-international.com\/es\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/es\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/es\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/annonce\/4302000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/types\/annonce"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/media?parent=4302000"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/secteurs?post=4302000"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/service?post=4302000"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/tags?post=4302000"},{"taxonomy":"type_de_bien","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/type_de_bien?post=4302000"},{"taxonomy":"type_annonce","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/type_annonce?post=4302000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}