{"id":3910213,"date":"2024-01-21T17:27:44","date_gmt":"2024-01-21T16:27:44","guid":{"rendered":"https:\/\/www.carlton-international.com\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/"},"modified":"2026-03-20T12:35:54","modified_gmt":"2026-03-20T11:35:54","slug":"cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette","status":"publish","type":"annonce","link":"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/","title":{"rendered":"Cannes &#8211; Excepcional villa belle epoque de 10 habitaciones en el centro de la Croisette"},"content":{"rendered":"<p>Una impresionante villa de la Belle \u00c9poque est\u00e1 disponible para alquilar en una tranquila zona residencial, estrat\u00e9gicamente enclavada cerca del coraz\u00f3n de Cannes. Esta exquisita propiedad ofrece la mezcla perfecta de opulencia y comodidad para aquellos que buscan un alojamiento cerca del Palais des Festivals, los famosos chiringuitos de Cannes y las boutiques.<\/p>\n<p>&#8212;<\/p>\n<p>La casa principal dispone de 8 habitaciones dobles con capacidad para 16 personas. Adem\u00e1s, una casa de invitados independiente de 2 dormitorios puede alojar a otros 4 hu\u00e9spedes o al personal. La villa cuenta con un amplio espacio para espect\u00e1culos, conferencias y exposiciones, incluida una magn\u00edfica zona de recepci\u00f3n triple de 60 metros que se abre a una espaciosa terraza de 60 m2 con vistas ininterrumpidas a la gran piscina. Entre las instalaciones m\u00e1s destacadas figuran una piscina de agua salada de 15 m x 5,50 m, WiFi de alta velocidad, vers\u00e1tiles salas de conferencias y exposiciones, e incluso una sala de cine. Adem\u00e1s, el hotel est\u00e1 a s\u00f3lo 10 minutos a pie del Palais des Festivals.<\/p>\n<p>La Villa ofrece la ventaja a\u00f1adida de estar a poca distancia de playas y restaurantes cercanos, lo que la convierte en un destino ideal para quienes buscan una escapada costera. Teniendo en cuenta la combinaci\u00f3n de comodidades modernas, esplendor arquitect\u00f3nico y amplios jardines muy cerca de la Croisette, pocas propiedades de alquiler pueden igualar la elegancia y la comodidad de la Villa. Reserve hoy mismo su estancia y disfrute como nunca del lujo cerca del Palais des Festivals de Cannes.<\/p>\n<p>Planta baja:<\/p>\n<p>&#8211; Hall de entrada con aseo doble para invitados y guardarropa.<br \/>\n&#8211; Sal\u00f3n triple con TV de plasma y acceso a la terraza.<br \/>\n&#8211; Comedor (20 personas) con vistas a la terraza y al jard\u00edn.<br \/>\n&#8211; Cocina totalmente equipada con 5 quemadores de gas, horno el\u00e9ctrico, nevera-congelador, lavavajillas, microondas, tostadora, m\u00e1quina Nespresso, robot de cocina multifunci\u00f3n, espumador de leche,<\/p>\n<p>Primera planta:<\/p>\n<p>&#8211; Dormitorio 1: cama doble (140 cm) con TV y caja fuerte. Cuarto de ba\u00f1o con ducha, inodoro y lavabo.<br \/>\n&#8211; Dormitorio 2: (dormitorio principal) cama doble (180 cm) con TV y caja fuerte. Cuarto de ba\u00f1o con ba\u00f1era, ducha, inodoro y lavabo doble.<br \/>\n&#8211; Dormitorio 3: camas individuales (2 x 90cm) con televisi\u00f3n y caja fuerte. Cuarto de ba\u00f1o con ducha, inodoro y lavabo.<br \/>\n&#8211; Dormitorio 4: cama individual (2 x 90cm) con televisi\u00f3n y caja fuerte. Cuarto de ba\u00f1o con ducha, inodoro y lavabo.<br \/>\n&#8211; Dormitorio 5: (Invitado principal) cama doble (1 x 180cm) con televisi\u00f3n y caja fuerte. Vestidor. Cuarto de ba\u00f1o con ducha, ba\u00f1era de hidromasaje, lavabo doble e inodoro.<\/p>\n<p>Segunda planta:<\/p>\n<p>&#8211; Dormitorio 6: Cama de matrimonio (180cm) y cama (1x 140cm) con vigas en el techo, televisi\u00f3n y caja fuerte. Cuarto de ba\u00f1o con ducha, ba\u00f1era, lavabo doble e inodoro.<br \/>\n&#8211; Dormitorio 7: cama doble (160cm) con televisi\u00f3n y caja fuerte. Cuarto de ba\u00f1o con ducha, lavabo e inodoro.<br \/>\n&#8211; Dormitorio 8: tres camas individuales (3x90cm) con televisi\u00f3n y caja fuerte. Cuarto de ba\u00f1o con ducha, inodoro y lavabo.<\/p>\n<p>Nivel jard\u00edn :<\/p>\n<p>&#8211; Aseo de invitados.<br \/>\n&#8211; Sauna<br \/>\n&#8211; Sala de fitness<br \/>\n&#8211; Cine en casa<br \/>\n&#8211; Sala de billar.<\/p>\n<p>Casa de invitados \/ Anexo :<\/p>\n<p>Planta baja:<br \/>\n&#8211; Sala de estar con TV,<br \/>\n&#8211; Comedor, cocina equipada (placa de inducci\u00f3n, horno, nevera-congelador, lavavajillas),<br \/>\n&#8211; Aseo de invitados.<\/p>\n<p>Primera planta de la casa de hu\u00e9spedes:<\/p>\n<p>&#8211; Dormitorio #1: cama doble (160cm), vestidor<br \/>\n&#8211; Dormitorio #2: camas individuales (2 x 90cm), vestidor<br \/>\n&#8211; Cuarto de ba\u00f1o, ba\u00f1era con ducha, lavabo, WC.<\/p>\n<p>Jard\u00edn :<\/p>\n<p>&#8211; Parque ajardinado, amplias terrazas.<br \/>\n&#8211; Aseo doble y ducha para invitados.<br \/>\n&#8211; Piscina climatizada de agua salada de 15m x 6m, terraza cubierta con mesas exteriores.<br \/>\n&#8211; Cocina de verano con horno, horno de pizza, microondas, m\u00e1quina de hielo, nevera doble, placa de cocci\u00f3n, lavavajillas, barbacoa de gas, freidora el\u00e9ctrica.<br \/>\nSal\u00f3n con p\u00e9rgola bioclim\u00e1tica.<br \/>\n&#8211; Amplia zona de recepci\u00f3n con suelo plano y p\u00e9rgola con sal\u00f3n de verano.<\/p>\n<p>Otras instalaciones:<br \/>\n&#8211; Aparcamiento para 6 coches.<br \/>\n&#8211; Alarma conectada a central de seguridad,<br \/>\n&#8211; Acceso a Internet de fibra \u00f3ptica de alta velocidad dentro y fuera.<br \/>\n&#8211; Aire acondicionado en toda la villa.<br \/>\n&#8211; Puerta autom\u00e1tica con videotel\u00e9fono<\/p>\n<p>Apto para: 20 personas.<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","secteurs":[3366,3369,5867,5960,1629,3368,5866],"service":[90,92,147,69,1295,359,97,103,160,133,71,93,1292,83],"tags":[8794,7895,89,4545,4546],"type_de_bien":[5860,1776],"type_annonce":[5878,1347],"class_list":["post-3910213","annonce","type-annonce","status-publish","hentry","secteurs-alpes-maritimes","secteurs-alpes-maritimes-en","secteurs-alpes-maritimes-es","secteurs-cannes-es","secteurs-cannes-en","secteurs-france-en","secteurs-france-es","service-air-conditionne","service-alarme","service-barbecue","service-cheminee","service-cinema","service-coffre-fort","service-eclairage-exterieur","service-fibre-optique","service-internet","service-maison-de-gardien","service-piscine","service-portail-electrique","service-salle-de-sport","service-sauna","tags-coups-de-coeur-ne-pas-toucher-audrey-uniquement","tags-site-carlton-international","tags-mer","tags-plateformes","tags-reseaux-sociaux","type_de_bien-hogar","type_de_bien-maison","type_annonce-alquiler-por-temporada","type_annonce-location-saisonniere"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cannes - Excepcional villa belle epoque de 10 habitaciones en el centro de la Croisette - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cannes - Excepcional villa belle epoque de 10 habitaciones en el centro de la Croisette\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T11:35:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/\",\"url\":\"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/\",\"name\":\"Cannes - Excepcional villa belle epoque de 10 habitaciones en el centro de la Croisette - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#website\"},\"datePublished\":\"2024-01-21T16:27:44+00:00\",\"dateModified\":\"2026-03-20T11:35:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cannes &#8211; Excepcional villa belle epoque de 10 habitaciones en el centro de la Croisette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/es\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cannes - Excepcional villa belle epoque de 10 habitaciones en el centro de la Croisette - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/","og_locale":"es_ES","og_type":"article","og_title":"Cannes - Excepcional villa belle epoque de 10 habitaciones en el centro de la Croisette","og_url":"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-03-20T11:35:54+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/","url":"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/","name":"Cannes - Excepcional villa belle epoque de 10 habitaciones en el centro de la Croisette - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/es\/#website"},"datePublished":"2024-01-21T16:27:44+00:00","dateModified":"2026-03-20T11:35:54+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/es\/annonce\/cannes-excepcional-villa-belle-epoque-de-10-habitaciones-en-el-centro-de-la-croisette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cannes &#8211; Excepcional villa belle epoque de 10 habitaciones en el centro de la Croisette"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/es\/#website","url":"https:\/\/www.carlton-international.com\/es\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/es\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/es\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/annonce\/3910213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/types\/annonce"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/media?parent=3910213"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/secteurs?post=3910213"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/service?post=3910213"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/tags?post=3910213"},{"taxonomy":"type_de_bien","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/type_de_bien?post=3910213"},{"taxonomy":"type_annonce","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/type_annonce?post=3910213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}