{"id":4311654,"date":"2026-02-25T09:58:30","date_gmt":"2026-02-25T08:58:30","guid":{"rendered":"https:\/\/www.carlton-international.com\/?post_type=agence&#038;p=4311654"},"modified":"2026-03-10T04:13:31","modified_gmt":"2026-03-10T03:13:31","slug":"saint-tropez","status":"publish","type":"agence","link":"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/","title":{"rendered":"Saint-Tropez"},"content":{"rendered":"<h3 style=\"text-align: left;\"><b>Nuestra agencia inmobiliaria en Saint-Tropez<\/b><\/h3>\n<p style=\"text-align: left;\"><strong>Carlton International<\/strong> encarna el lujo y la elegancia en el coraz\u00f3n del casco antiguo de Saint-Tropez, especializ\u00e1ndose en la <strong>venta de propiedades de prestigio<\/strong> y en el <strong>alquiler de temporada y de larga duraci\u00f3n<\/strong> de propiedades excepcionales. Bajo la experimentada direcci\u00f3n de <strong>Corinne Aigouy<\/strong>, una profesional presente desde hace m\u00e1s de 15 a\u00f1os en la agencia, el equipo cuenta con una experiencia inigualable en el mercado \u00fanico de <a href=\"https:\/\/www.carlton-international.com\/fr\/ville\/saint_tropez\"><strong>Saint-Tropez<\/strong><\/a>.<\/p>\n<p style=\"text-align: left;\">Reconocido por sus playas, su puerto y su escena gastron\u00f3mica, este destino es el escenario ideal para sus proyectos inmobiliarios. La satisfacci\u00f3n del cliente es la prioridad absoluta, con un servicio a medida que ofrece una experiencia inmobiliaria integral. Para hacer realidad sus aspiraciones en Saint-Tropez, contacte con <strong>Carlton International<\/strong>, miembro del grupo Carlton Group, y sum\u00e9rjase en esta experiencia excepcional.<\/p>\n<p style=\"text-align: left;\"><strong>Acerca de Carlton International<\/strong><\/p>\n<p style=\"text-align: left;\">Carlton International es mucho m\u00e1s que una simple agencia inmobiliaria. Somos un equipo dedicado de profesionales apasionados por el sector inmobiliario de alta gama. Nuestro equipo de m\u00e1s de 25 expertos est\u00e1 perfectamente posicionado para responder a sus exigencias en materia de compra, venta y alquiler de propiedades de prestigio.<\/p>\n<p style=\"text-align: left;\"><strong>Nuestro compromiso con la excelencia<\/strong><\/p>\n<p style=\"text-align: left;\">En Carlton International creemos en la excelencia en todo lo que hacemos. Por ello, nos esforzamos por superar sus expectativas en cada etapa. Desde la primera consulta hasta el cierre de la transacci\u00f3n, nuestro equipo se compromete a ofrecer un servicio excepcional a cada cliente. Como cada propiedad y cada cliente son \u00fanicos, ofrecemos un servicio personalizado para responder a sus necesidades espec\u00edficas.<\/p>\n<p style=\"text-align: left;\"><strong>Una selecci\u00f3n de propiedades exclusivas<\/strong><\/p>\n<p style=\"text-align: left;\">Ya sea que busque una villa frente al mar con vistas al Mediterr\u00e1neo o una propiedad de lujo en las colinas del interior, Carlton International tiene lo que necesita. Nuestro portafolio exclusivo est\u00e1 cuidadosamente seleccionado para ofrecerle las mejores opciones disponibles en el mercado.<\/p>\n<p style=\"text-align: left;\"><strong>Cont\u00e1ctenos<\/strong><\/p>\n<p style=\"text-align: left;\">Cont\u00e1ctenos hoy mismo para hacer realidad sus proyectos inmobiliarios.<\/p>\n","protected":false},"featured_media":3444702,"menu_order":0,"template":"","secteurs":[],"class_list":["post-4311654","agence","type-agence","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Saint-Tropez - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saint-Tropez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T03:13:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/image-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/\",\"url\":\"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/\",\"name\":\"Saint-Tropez - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/image-1.png\",\"datePublished\":\"2026-02-25T08:58:30+00:00\",\"dateModified\":\"2026-03-10T03:13:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/#primaryimage\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/image-1.png\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/image-1.png\",\"width\":1280,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saint-Tropez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/es\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Saint-Tropez - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/","og_locale":"es_ES","og_type":"article","og_title":"Saint-Tropez","og_url":"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-03-10T03:13:31+00:00","og_image":[{"width":1280,"height":850,"url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/image-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/","url":"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/","name":"Saint-Tropez - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/#primaryimage"},"image":{"@id":"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/image-1.png","datePublished":"2026-02-25T08:58:30+00:00","dateModified":"2026-03-10T03:13:31+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/#primaryimage","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/image-1.png","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2025\/06\/image-1.png","width":1280,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/es\/agence\/saint-tropez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/es\/"},{"@type":"ListItem","position":2,"name":"Saint-Tropez"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/es\/#website","url":"https:\/\/www.carlton-international.com\/es\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/es\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/es\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/agence\/4311654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/agence"}],"about":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/types\/agence"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/media\/3444702"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/media?parent=4311654"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/es\/wp-json\/wp\/v2\/secteurs?post=4311654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}