{"id":4620,"count":53,"description":"","link":"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/","name":"Marbella","slug":"marbella-en","taxonomy":"secteurs","parent":4599,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marbella - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marbella\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/\",\"url\":\"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/\",\"name\":\"Marbella - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espagne\",\"item\":\"https:\/\/www.carlton-international.com\/en\/secteurs\/espagne-pt\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marbella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/en\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marbella - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/","og_locale":"en_US","og_type":"article","og_title":"Marbella","og_url":"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/","og_site_name":"Carlton International","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/","url":"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/","name":"Marbella - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/en\/secteurs\/marbella-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/en\/"},{"@type":"ListItem","position":2,"name":"Espagne","item":"https:\/\/www.carlton-international.com\/en\/secteurs\/espagne-pt\/"},{"@type":"ListItem","position":3,"name":"Marbella"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/en\/#website","url":"https:\/\/www.carlton-international.com\/en\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/en\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/en\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/secteurs\/4620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/secteurs"}],"about":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/taxonomies\/secteurs"}],"up":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/secteurs\/4599"}],"wp:post_type":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/annonce?secteurs=4620"},{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/agence?secteurs=4620"},{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/zone?secteurs=4620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}