{"id":3352166,"date":"2025-05-22T06:46:33","date_gmt":"2025-05-22T04:46:33","guid":{"rendered":"https:\/\/www.carlton-international.com\/?page_id=3352166"},"modified":"2025-05-26T10:19:54","modified_gmt":"2025-05-26T08:19:54","slug":"cap-dail","status":"publish","type":"page","link":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/","title":{"rendered":"Cap d&#8217;Ail"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3352166\" class=\"elementor elementor-3352166 elementor-3333991\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a9634d contentpd30 e-flex e-con-boxed e-con e-parent\" data-id=\"7a9634d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div data-dce-title-color=\"#BFA473\" class=\"elementor-element elementor-element-eb0326c elementor-widget elementor-widget-heading\" data-id=\"eb0326c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cap d'Ail<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-792e6aa7 contentpd20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"792e6aa7\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ab2cffd\" data-id=\"4ab2cffd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f80d67 elementor-widget elementor-widget-shortcode\" data-id=\"3f80d67\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">    <div class=\"ci-dis-ads_wrapper\" data-id-page=\"3352166\" id=\"ci-ads-results\">\n                <!-- TOTAL RESULTS -->\n        <div class=\"ci-dis-ads_total_results aa\">\n            <div class=\"ci-dis-description_contact_results a2345 3352166\">\n            \n                <p>\n                <a href=\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/\">carlton international luxury villa collection<\/a> &gt; <a href=\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/\">luxury rental properties on the c\u00f4te d&#8217;azur<\/a> &gt; <a href=\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/\">luxury rentals in the south of france<\/a> &gt; <a href=\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/\">luxury rental properties near nice<\/a> &gt; <a href=\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/\">cap d&#8217;ail<\/a> &gt; <span data-id=\"3352166\">0 r\u00e9sultat<\/span>                <\/p>\n                            <\/div>\n        <\/div>\n                    <!-- HEADER -->\n            <div class=\"ci-dis-ads_header\">\n                <!-- PAGINATION -->\n                <div class=\"ci-dis-ads_pagination\">\n                                    <\/div>\n                <!-- SORT -->\n\n                                    <div class=\"ci-dis-ads_sort\">\n                                            <\/div>\n                    <!-- DISPLAY -->\n                    <div class=\"ci-dis-ads_disp\">\n                                            <\/div>\n                            <\/div>\n                <!-- CONTENT -->\n        <div class=\"ci-dis-ads_content ci-disp-grid\">\n                                                                    <div class=\"ci-dis-ads_content-empty s1\" style=\"display: flex;\">\n                                        <p class=\"ci-dis-ads_content-empty_text\"><\/p>\n                                        <div><div>\n<div>Many properties matching your search are marketed in a <strong>strictly confidential off-market framework, directly by our teams.<\/strong><\/div>\n<div>We invite you to contact the <strong>Carlton International agency corresponding to the address you are seeking<\/strong> in order to access these exclusive opportunities : <a href=\"https:\/\/www.carlton-international.com\/en\/contact-us\/\">https:\/\/www.carlton-international.com\/en\/contact-us\/<\/a><\/div>\n<\/div>\n<\/div>\n                                    <\/div>\n                                                            \n                                                <\/div>\n        <!-- FOOTER -->\n        <div class=\"ci-dis-ads_footer\">\n            <!-- PAGINATION -->\n            <div class=\"ci-dis-ads_pagination\">\n                            <\/div>\n        <\/div>\n                 <\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":934516,"parent":961856,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"class_list":["post-3352166","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cap d&#039;Ail - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cap d&#039;Ail\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-26T08:19:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"649\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/\",\"url\":\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/\",\"name\":\"Cap d'Ail - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg\",\"datePublished\":\"2025-05-22T04:46:33+00:00\",\"dateModified\":\"2025-05-26T08:19:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/#primaryimage\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg\",\"width\":649,\"height\":487,\"caption\":\"Luxury Villas In Cannes Countryside\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carlton International Luxury Villa Collection\",\"item\":\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luxury Rental Properties On The C\u00f4te d&#8217;Azur\",\"item\":\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Luxury Rentals In the South of France\",\"item\":\"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Luxury Rental Properties Near Nice\",\"item\":\"https:\/\/www.carlton-international.com\/en\/collections-location\/cote-dazur\/location-saisonniere\/nice-environs\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Cap d&#8217;Ail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/en\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cap d'Ail - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/","og_locale":"en_US","og_type":"article","og_title":"Cap d'Ail","og_url":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2025-05-26T08:19:54+00:00","og_image":[{"width":649,"height":487,"url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/","url":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/","name":"Cap d'Ail - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/#primaryimage"},"image":{"@id":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg","datePublished":"2025-05-22T04:46:33+00:00","dateModified":"2025-05-26T08:19:54+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/#primaryimage","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/07\/arriere-pays3_65815.jpeg","width":649,"height":487,"caption":"Luxury Villas In Cannes Countryside"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/luxury-rental-properties-near-nice\/cap-dail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/en\/"},{"@type":"ListItem","position":2,"name":"Carlton International Luxury Villa Collection","item":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/"},{"@type":"ListItem","position":3,"name":"Luxury Rental Properties On The C\u00f4te d&#8217;Azur","item":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/"},{"@type":"ListItem","position":4,"name":"Luxury Rentals In the South of France","item":"https:\/\/www.carlton-international.com\/en\/luxury-rental-villas-on-the-french-riviera\/luxury-rental-properties-on-the-cote-dazur\/luxury-rentals-in-the-south-of-france\/"},{"@type":"ListItem","position":5,"name":"Luxury Rental Properties Near Nice","item":"https:\/\/www.carlton-international.com\/en\/collections-location\/cote-dazur\/location-saisonniere\/nice-environs\/"},{"@type":"ListItem","position":6,"name":"Cap d&#8217;Ail"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/en\/#website","url":"https:\/\/www.carlton-international.com\/en\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/en\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/en\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/pages\/3352166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/comments?post=3352166"}],"version-history":[{"count":0,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/pages\/3352166\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/pages\/961856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/media\/934516"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/media?parent=3352166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}