{"id":3142461,"date":"2020-03-05T10:55:13","date_gmt":"2020-03-05T09:55:13","guid":{"rendered":"https:\/\/www.carlton-international.com\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/"},"modified":"2026-04-17T00:14:15","modified_gmt":"2026-04-16T22:14:15","slug":"new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer","status":"publish","type":"annonce","link":"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/","title":{"rendered":"New Ultra-Modern Villa, Stunning Views, Pool, Wine Cellar, Theoule-sur-Mer"},"content":{"rendered":"<p>Newly completed ultra-modern contemporary villa located on the hill above Miramar Beach, in absolute calm. Located in a gated residential estate.  Panoramic sea view over the entire bay of Cannes, Cap d&#8217;Antibes, StJean Cap Ferrat and into Italy on a clear day. Truly spectacular view.<\/p>\n<p>Enter into the open kitchen, living, dining room with high ceilings allowing light to flood the voluminous elegant space showcasing a large, climate-controlled, wine cellar.  <\/p>\n<p>On two levels and with a living area of \u200b\u200bapproximately 300 m\u00b2, the home includes 5 en-suite bedrooms, including the primary bedroom with deep, sunken tub for 2, chic, tiled shower, large dressing room and dual-paned gas fireplace. Every bedroom features a spectacular view from the floor to ceiling windows of the Mediterranean Sea over the Cap d&#8217;Antibes and Nice. <\/p>\n<p>This custom built home features, under-floor heating, reversible air conditioning, summer kitchen, gas fireplaces, sprawling terraces, heated pool, separate &#8220;pantry&#8221; and guest quarters with independent and separate access.<\/p>\n<p>Landscaped grounds of 1475 m\u00b2, decorated, at each level, with furnished terraces.  A &#8220;Mirror&#8221; pool is on the roof terrace. Triple garage, parking spaces.<\/p>\n<p>Idyllic environment, greenery, and serenity are at the rendezvous.  Ref: 8534.<\/p>\n<p>The average energy expenditure in 2021  is between 1400 \u20ac and 1940 \u20ac per year.<br \/>\nAgency fees are at the expense of the seller. <\/p>\n<p>Information on the risks to which this property is exposed is available on the GeoHazards website http:\/\/www.georisques.gouv.fr<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","secteurs":[3369,3366,3368,8856,3365,1394,1683],"service":[90,92,96,102,69,72,97,73,71,87,1294,94,88],"tags":[7896,7897,8829,2071,2035,2062,4084,4081,4087,2033,2027],"type_de_bien":[1777,1776],"type_annonce":[4525,4526],"class_list":["post-3142461","annonce","type-annonce","status-publish","hentry","secteurs-alpes-maritimes-en","secteurs-alpes-maritimes","secteurs-france-en","secteurs-france-pt","secteurs-france","secteurs-theoule-sur-mer","secteurs-theoule-sur-mer-en","service-air-conditionne","service-alarme","service-arrosage","service-ascenseur","service-cheminee","service-double-vitrage","service-eclairage-exterieur","service-fenetres-coulissantes","service-piscine","service-porte-blindee","service-thermostat-connecte","service-video-surveillance","service-videophone","tags-diagnostiques-techniques","tags-passeport-id","tags-vue-mer","tags-aucun-vis-a-vis-en","tags-cadre-silencieux-en","tags-chambre-staff-en","tags-contemporaine","tags-domaine-ferme","tags-domaine-securise","tags-mer-en","tags-quartier-residentiel-en","type_de_bien-house","type_de_bien-maison","type_annonce-achat","type_annonce-buy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>New Ultra-Modern Villa, Stunning Views, Pool, Wine Cellar, Theoule-sur-Mer - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Ultra-Modern Villa, Stunning Views, Pool, Wine Cellar, Theoule-sur-Mer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T22:14:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/\",\"url\":\"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/\",\"name\":\"New Ultra-Modern Villa, Stunning Views, Pool, Wine Cellar, Theoule-sur-Mer - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#website\"},\"datePublished\":\"2020-03-05T09:55:13+00:00\",\"dateModified\":\"2026-04-16T22:14:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New Ultra-Modern Villa, Stunning Views, Pool, Wine Cellar, Theoule-sur-Mer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/en\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"New Ultra-Modern Villa, Stunning Views, Pool, Wine Cellar, Theoule-sur-Mer - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/","og_locale":"en_US","og_type":"article","og_title":"New Ultra-Modern Villa, Stunning Views, Pool, Wine Cellar, Theoule-sur-Mer","og_url":"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-04-16T22:14:15+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/","url":"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/","name":"New Ultra-Modern Villa, Stunning Views, Pool, Wine Cellar, Theoule-sur-Mer - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/en\/#website"},"datePublished":"2020-03-05T09:55:13+00:00","dateModified":"2026-04-16T22:14:15+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/en\/annonce\/new-ultra-modern-villa-stunning-views-pool-wine-cellar-theoule-sur-mer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/en\/"},{"@type":"ListItem","position":2,"name":"New Ultra-Modern Villa, Stunning Views, Pool, Wine Cellar, Theoule-sur-Mer"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/en\/#website","url":"https:\/\/www.carlton-international.com\/en\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/en\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/en\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/annonce\/3142461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/types\/annonce"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/media?parent=3142461"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/secteurs?post=3142461"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/service?post=3142461"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/tags?post=3142461"},{"taxonomy":"type_de_bien","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/type_de_bien?post=3142461"},{"taxonomy":"type_annonce","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/type_annonce?post=3142461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}