{"id":3131851,"date":"2025-03-05T17:22:50","date_gmt":"2025-03-05T16:22:50","guid":{"rendered":"https:\/\/www.carlton-international.com\/annonce\/charming-new-villa-saint-tropez\/"},"modified":"2026-03-20T12:55:27","modified_gmt":"2026-03-20T11:55:27","slug":"charming-new-villa-saint-tropez","status":"publish","type":"annonce","link":"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/","title":{"rendered":"Charming new villa &#8211; Saint-Tropez"},"content":{"rendered":"<p>Saint-Tropez &#8211; Close to the village and on the way to the beaches of Pampelonne, this new 190 m2 villa offers a magnificent, peaceful setting for unforgettable vacations.<\/p>\n<p>With its four elegantly appointed en suite bedrooms, it&#8217;s ideal for welcoming families and friends in a cosy, chic decor.  <\/p>\n<p>The villa boasts a magnificent swimming pool, perfect for cooling off on sunny days, and a pool house with summer kitchen.<\/p>\n<p>Petanque court for convivial moments.<br \/>\nYou&#8217;ll benefit from modern amenities, such as an advanced home automation system, alarm system, surveillance cameras and electric gate.<br \/>\nRef ST2510<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","secteurs":[8856,8856,3368,1275,1626,3370,3367],"service":[90,92,96,1376,69,91,70,97,160,104,363,1390,71,93,1292,1384,145,94,101],"tags":[7897,7904,7895,2071,2035,2065,2033,4545,4546,2097,4550],"type_de_bien":[1777,8478],"type_annonce":[1348,1348],"class_list":{"0":"post-3131851","1":"annonce","2":"type-annonce","3":"status-publish","4":"hentry","5":"secteurs-france-pt","7":"secteurs-france-en","8":"secteurs-saint-tropez","9":"secteurs-saint-tropez-en","10":"secteurs-var-en","11":"secteurs-var","12":"service-air-conditionne","13":"service-alarme","14":"service-arrosage","15":"service-borne-voiture-electrique","16":"service-cheminee","17":"service-cloture","18":"service-domotique","19":"service-eclairage-exterieur","20":"service-internet","21":"service-interphone","22":"service-jeu-de-boules","23":"service-linge-de-maison","24":"service-piscine","25":"service-portail-electrique","26":"service-salle-de-sport","27":"service-triple-vitrage","28":"service-vide-sanitaire","29":"service-video-surveillance","30":"service-volets-roulants-electriques","31":"tags-passeport-id","32":"tags-permis-de-construire","33":"tags-site-carlton-international","34":"tags-aucun-vis-a-vis-en","35":"tags-cadre-silencieux-en","36":"tags-espace-fitness-en","37":"tags-mer-en","38":"tags-plateformes","39":"tags-reseaux-sociaux","40":"tags-service-femme-de-menage-en","41":"tags-titre-de-propriete","42":"type_de_bien-house","43":"type_de_bien-maison-en","44":"type_annonce-seasonal-rental"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Charming new villa - Saint-Tropez - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Charming new villa - Saint-Tropez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T11:55:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/\",\"url\":\"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/\",\"name\":\"Charming new villa - Saint-Tropez - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#website\"},\"datePublished\":\"2025-03-05T16:22:50+00:00\",\"dateModified\":\"2026-03-20T11:55:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Charming new villa &#8211; Saint-Tropez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/en\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Charming new villa - Saint-Tropez - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/","og_locale":"en_US","og_type":"article","og_title":"Charming new villa - Saint-Tropez","og_url":"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-03-20T11:55:27+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/","url":"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/","name":"Charming new villa - Saint-Tropez - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/en\/#website"},"datePublished":"2025-03-05T16:22:50+00:00","dateModified":"2026-03-20T11:55:27+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/en\/annonce\/charming-new-villa-saint-tropez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/en\/"},{"@type":"ListItem","position":2,"name":"Charming new villa &#8211; Saint-Tropez"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/en\/#website","url":"https:\/\/www.carlton-international.com\/en\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/en\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/en\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/annonce\/3131851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/types\/annonce"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/media?parent=3131851"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/secteurs?post=3131851"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/service?post=3131851"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/tags?post=3131851"},{"taxonomy":"type_de_bien","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/type_de_bien?post=3131851"},{"taxonomy":"type_annonce","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/type_annonce?post=3131851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}