{"id":1977133,"date":"2011-03-09T16:16:57","date_gmt":"2011-03-09T15:16:57","guid":{"rendered":"https:\/\/www.carlton-international.com\/annonce\/les-marres-2\/"},"modified":"2026-03-20T12:53:50","modified_gmt":"2026-03-20T11:53:50","slug":"les-marres","status":"publish","type":"annonce","link":"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/","title":{"rendered":"&#8220;Les Marres&#8221;"},"content":{"rendered":"<p>SAINT TROPEZ &#8211; Situated in the sought-after Marres area, halfway between the beaches of Pampelonne and the town centre, with a beautiful view of the sea and hills, this superb villa welcomes you to a peaceful setting and idyllic holiday location.<\/p>\n<p>Built in the modern Provencal style, the 650 m\u00b2 house offers generous living space, comprising a double living room with fireplace, dining room, separate kitchen with terrace, 7 bedrooms including a master, 7 bathrooms, dressing rooms, 1 utility room and laundry room. 1 sports room, 1 high-tech cinema (10 seats), 1 games room, sauna, hammam, jacuzzi. The rooms are bathed in light thanks to large bay windows.<\/p>\n<p>There is a large terrace overlooking the mirror pool with a summer bar and lounge.   Housekeeper 7\/7. Garage. ST1116<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","secteurs":[3368,8856,3365,1330,1658,3367,3370],"service":[146,90,92,96,147,69,359,357,108,70,97,73,1600,160,82,363,1390,71,93,83,84,95],"tags":[9113,7895,2071,2035,2062,4084,2030,2065,3897,2064,2243,2033,2239,4545,2027,4546,2098,2242,2097],"type_de_bien":[1777,1776],"type_annonce":[1347,1348],"class_list":["post-1977133","annonce","type-annonce","status-publish","hentry","secteurs-france-en","secteurs-france-pt","secteurs-france","secteurs-ramatuelle","secteurs-ramatuelle-en","secteurs-var","secteurs-var-en","service-abri-de-voiture","service-air-conditionne","service-alarme","service-arrosage","service-barbecue","service-cheminee","service-coffre-fort","service-concierge","service-digicode","service-domotique","service-eclairage-exterieur","service-fenetres-coulissantes","service-heliport","service-internet","service-jacuzzi","service-jeu-de-boules","service-linge-de-maison","service-piscine","service-portail-electrique","service-sauna","service-spa","service-stores-electriques","tags-newsletter","tags-site-carlton-international","tags-aucun-vis-a-vis-en","tags-cadre-silencieux-en","tags-chambre-staff-en","tags-contemporaine","tags-espace-bien-etre-en","tags-espace-fitness-en","tags-hammam","tags-home-cinema-en","tags-jacuzzi","tags-mer-en","tags-piscine-chauffee","tags-plateformes","tags-quartier-residentiel-en","tags-reseaux-sociaux","tags-salle-de-massage-en","tags-sauna","tags-service-femme-de-menage-en","type_de_bien-house","type_de_bien-maison","type_annonce-location-saisonniere","type_annonce-seasonal-rental"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Les Marres&quot; - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Les Marres&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T11:53:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/\",\"url\":\"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/\",\"name\":\"\\\"Les Marres\\\" - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#website\"},\"datePublished\":\"2011-03-09T15:16:57+00:00\",\"dateModified\":\"2026-03-20T11:53:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0Les Marres\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/en\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Les Marres\" - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/","og_locale":"en_US","og_type":"article","og_title":"\"Les Marres\"","og_url":"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-03-20T11:53:50+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/","url":"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/","name":"\"Les Marres\" - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/en\/#website"},"datePublished":"2011-03-09T15:16:57+00:00","dateModified":"2026-03-20T11:53:50+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/en\/annonce\/les-marres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0Les Marres\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/en\/#website","url":"https:\/\/www.carlton-international.com\/en\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/en\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/en\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/annonce\/1977133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/types\/annonce"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/media?parent=1977133"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/secteurs?post=1977133"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/service?post=1977133"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/tags?post=1977133"},{"taxonomy":"type_de_bien","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/type_de_bien?post=1977133"},{"taxonomy":"type_annonce","embeddable":true,"href":"https:\/\/www.carlton-international.com\/en\/wp-json\/wp\/v2\/type_annonce?post=1977133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}