{"id":3600122,"date":"2025-02-28T08:16:19","date_gmt":"2025-02-28T07:16:19","guid":{"rendered":"https:\/\/www.carlton-international.com\/zone\/proche-de-monaco\/"},"modified":"2025-07-11T15:55:21","modified_gmt":"2025-07-11T13:55:21","slug":"proche-de-monaco","status":"publish","type":"zone","link":"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/","title":{"rendered":"Proche De Monaco"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"menu_order":12,"template":"","secteurs":[5933,5929,5935,5931,5937,5927,5895,5923,5990,5921],"class_list":["post-3600122","zone","type-zone","status-publish","hentry","secteurs-beaulieu-sur-mer-de","secteurs-beausoleil-de","secteurs-cap-dail-de","secteurs-eze-de","secteurs-la-turbie-de","secteurs-menton-de","secteurs-nice-de","secteurs-roquebrune-cap-martin-de","secteurs-saint-jean-cap-ferrat-de","secteurs-villefranche-sur-mer-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Proche De Monaco - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proche De Monaco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T13:55:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/\",\"url\":\"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/\",\"name\":\"Proche De Monaco - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\"},\"datePublished\":\"2025-02-28T07:16:19+00:00\",\"dateModified\":\"2025-07-11T13:55:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proche De Monaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Proche De Monaco - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/","og_locale":"de_DE","og_type":"article","og_title":"Proche De Monaco","og_url":"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2025-07-11T13:55:21+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/","url":"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/","name":"Proche De Monaco - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/de\/#website"},"datePublished":"2025-02-28T07:16:19+00:00","dateModified":"2025-07-11T13:55:21+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/de\/zone\/proche-de-monaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/de\/"},{"@type":"ListItem","position":2,"name":"Proche De Monaco"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/de\/#website","url":"https:\/\/www.carlton-international.com\/de\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/de\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/de\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/zone\/3600122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/zone"}],"about":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/types\/zone"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/media?parent=3600122"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/secteurs?post=3600122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}