{"id":3910269,"date":"2024-02-07T18:38:31","date_gmt":"2024-02-07T17:38:31","guid":{"rendered":"https:\/\/www.carlton-international.com\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/"},"modified":"2026-03-20T12:36:01","modified_gmt":"2026-03-20T11:36:01","slug":"roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt","status":"publish","type":"annonce","link":"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/","title":{"rendered":"Roquebrune-Cap-Martin &#8211; Luxusvilla mit 5 Schlafzimmern, 5 Minuten von Monaco entfernt"},"content":{"rendered":"<p>Diese beeindruckende moderne Villa bietet Platz f\u00fcr bis zu 13 Personen. Sie erstreckt sich \u00fcber 800 m2 und bietet einen atemberaubenden Blick auf das Mittelmeer und Monaco. Eingebettet in eine private und \u00fcppige Umgebung liegt sie weniger als zehn Autominuten von Monte Carlo entfernt. Dieses Ferienrefugium wurde 2021 frisch mit hochwertiger Ausstattung renoviert und 2022 mit viel Liebe zum Detail m\u00f6bliert und strahlt ein pr\u00e4chtiges, vom Art d\u00e9co inspiriertes Ambiente aus. Diese am Stadtrand von Monaco gelegene Luxusvilla kann nun gemietet werden und ist eine erstklassige Adresse an der C\u00f4te d&#8217;Azur.<\/p>\n<p>Auf einer Fl\u00e4che von 800 m2 verf\u00fcgt die Villa \u00fcber vier Schlafzimmer, die alle nach S\u00fcden ausgerichtet sind und einen dreifachen Blick auf die bewaldete Umgebung, das Mittelmeer und Monaco bieten. Jedes Zimmer \u00f6ffnet sich zu einer nach S\u00fcden ausgerichteten Terrasse, die mit elektrischen Jalousien ausgestattet ist, um sich vor der Sonne zu sch\u00fctzen. Dar\u00fcber hinaus verf\u00fcgen alle Zimmer \u00fcber ein eigenes Badezimmer mit begehbarer Dusche.<\/p>\n<p>Das Anwesen ist dank eines Domotiksystems, das Vorh\u00e4nge, Rolll\u00e4den, Fu\u00dfbodenheizung, Klimaanlage, Beleuchtung und Multimedia steuert, vollst\u00e4ndig automatisiert. Eine Hochgeschwindigkeits-Internetverbindung ist ebenfalls verf\u00fcgbar.<\/p>\n<p>Neben den gro\u00dfen Sonnenterrassen schafft ein gro\u00dfer gepflasterter Innenhof neben dem 68 Quadratmeter gro\u00dfen Pool einen idealen Raum f\u00fcr Versammlungen im Freien. Die gepflegten G\u00e4rten mit Rasenfl\u00e4chen, Str\u00e4uchern und reifen B\u00e4umen bieten ruhige Ecken zum Entspannen. Auf dem landschaftlich gestalteten Grundst\u00fcck stehen zahlreiche Parkpl\u00e4tze zur Verf\u00fcgung, darunter eine ger\u00e4umige Garage f\u00fcr sechs Autos.<\/p>\n<p>Die Villa war fr\u00fcher eine Privatresidenz und belegt nun ein ca. 3.870 Quadratmeter gro\u00dfes Grundst\u00fcck am Hang, das Ruhe bietet und dennoch in der N\u00e4he von Monaco liegt. Die Immobilie liegt ideal in der N\u00e4he der Autobahn A8 und bietet einen einfachen Zugang zur italienischen Grenze, nach Nizza und zum Flughafen Nizza C\u00f4te d&#8217;Azur. Es eignet sich perfekt f\u00fcr diejenigen, die einen privaten R\u00fcckzugsort suchen, der nur wenige Minuten vom Zentrum Monacos entfernt ist und eine ruhige Flucht am Pool unter der Mittelmeersonne erm\u00f6glicht. Ein Fu\u00dfweg vom Anwesen f\u00fchrt in die Stadt und bietet die M\u00f6glichkeit f\u00fcr einen morgendlichen Spaziergang, um einen Kaffee in der Stadt zu trinken.<\/p>\n<p>Auf den beiden Etagen der Villa befinden sich die wichtigsten Empfangsr\u00e4ume und Schlafzimmer, die alle so gestaltet sind, dass Sie die atemberaubende Aussicht in vollen Z\u00fcgen genie\u00dfen k\u00f6nnen. Das mit einem 100-Zoll-Fernseher ausgestattete Wohnzimmer wird durch ein Spielzimmer mit Spiegelw\u00e4nden, eine wundersch\u00f6ne Eingangshalle und ein ger\u00e4umiges Esszimmer mit einem Kamin im Art-Deco-Stil erg\u00e4nzt. Der formelle Speisesaal bietet Platz f\u00fcr 12 Personen und 20 weitere Personen. Ein Spielzimmer mit Tischfu\u00dfball und Billardtisch bietet weitere Unterhaltungsm\u00f6glichkeiten. Die voll ausgestattete K\u00fcche, die auch als ungezwungener Speisesaal dient, ist mit modernen Ger\u00e4ten ausgestattet, darunter eine Kaffeemaschine, ein Weink\u00fchler und mehrere K\u00fchlschr\u00e4nke.<\/p>\n<p>Das Anwesen verf\u00fcgt au\u00dferdem \u00fcber eine zweite Sommerk\u00fcche und eine Waschk\u00fcche. Es ist mit einem audiovisuellen Unterhaltungssystem ausgestattet, das Apple TV, Kartina TV, Tischfu\u00dfball, Billard, Tischtennis und Badmintonausr\u00fcstung umfasst. Auf der Dachterrasse steht ein astronomisches Teleskop zur Verf\u00fcgung, mit dem Sie die Sterne beobachten k\u00f6nnen. Die Au\u00dfenbereiche sind auf Entspannung ausgelegt, sei es beim Sonnenbaden auf Liegest\u00fchlen, beim Sitzen unter Sonnenschirmen oder beim abendlichen Grillen. F\u00fcr Fitnessbegeisterte steht ein voll ausgestattetes Fitnessstudio mit einem Dampfbad und einem Massageraum mit beheizter Massageliege in Profiqualit\u00e4t zur Verf\u00fcgung. Das Hauptschlafzimmer ist mit einer Sauna und einem Whirlpool ausgestattet, die f\u00fcr optimale Entspannung sorgen.<\/p>\n<p>Um Ihren Aufenthalt noch angenehmer zu gestalten, bietet das Anwesen verschiedene Dienstleistungen im Rahmen der Vermietung an:<\/p>\n<p>Chefkoch: Ein Chefkoch steht Ihnen sieben Tage die Woche f\u00fcr Fr\u00fchst\u00fcck, Mittag- und Abendessen zur Verf\u00fcgung.<br \/>\nChauffeur: Ein Fahrer in einem Mercedes Viano steht acht Stunden am Tag, f\u00fcnf Tage die Woche zur Verf\u00fcgung, um nach Monte Carlo zu fahren.<br \/>\nZimmerm\u00e4dchen: T\u00e4gliche diskrete Haushaltsdienstleistungen, einschlie\u00dflich eines Zimmervorbereitungsdienstes.<br \/>\nG\u00e4rtner: Der Garten wird zweimal pro Woche gepflegt.<br \/>\nSicherheit: Sicherheitspersonal ist 24 Stunden am Tag und 7 Tage die Woche vor Ort.<br \/>\nFlughafentransfer: Ein Abhol- und R\u00fcckbringservice vom Flughafen Nizza ist inbegriffen.<br \/>\nWifi: Stabile und zuverl\u00e4ssige Internetverbindung.<\/p>\n<p>Wichtigste Merkmale :<\/p>\n<p>Bietet Platz f\u00fcr 10 Personen in 5 Doppelzimmern + 3 zus\u00e4tzliche Personen in Einzelbetten.<br \/>\n5 Schlafzimmer mit angrenzenden Badezimmern (3 zus\u00e4tzliche Einzelbetten verf\u00fcgbar).<br \/>\nEin G\u00e4stezimmer \/ Dienstm\u00e4dchenzimmer mit eigenem Zugang &#8211; f\u00fcr 2 Personen.<br \/>\nMastersuite mit Ankleidezimmer, Sauna und B\u00fcro.<br \/>\nVoll ausgestatteter Fitnessraum, Dampfbad, Sauna und Massageraum.<br \/>\nGro\u00dfes offenes Wohnzimmer mit 100-Zoll-Fernseher, Kamin und Spielbereich.<br \/>\nEsszimmer mit Platz f\u00fcr bis zu 22 Personen.<br \/>\nK\u00fcchen im Innen- und Au\u00dfenbereich.<br \/>\nSicherer Innenparkplatz f\u00fcr 6 Autos.<br \/>\nUnterk\u00fcnfte f\u00fcr das Personal.<br \/>\nAufzugzugang von der Garage zum Wohnzimmer.<br \/>\nDomotisches System.<br \/>\nKlimaanlage und Fu\u00dfbodenheizung im gesamten Haus.<br \/>\n68 m\u00b2 gro\u00dfer, geschnitzter Pool.<br \/>\nTerrassen mit Panoramablick.<br \/>\nErh\u00f6hte Esszimmer im Freien mit Blick auf das Meer.<br \/>\nVollst\u00e4ndig integriertes Sicherheitssystem.<br \/>\nAu\u00dfenparkplatz f\u00fcr mehr als 8 Autos.<br \/>\nSafe in jedem Schlafzimmer.<\/p>\n<p>Eingeschlossenes Personal :<br \/>\nVerwalter der Villa (24\/7).<br \/>\nHausmeister (24\/7)<br \/>\n1 Haush\u00e4lterin (24\/7)<br \/>\n1 Haush\u00e4lterin (08.00-17.00 Uhr)<br \/>\nKoch deckt Fr\u00fchst\u00fcck, Mittag- und Abendessen ab &#8211; Sicherheitsdienst (24\/7)<br \/>\nChauffeur (steht 8 Stunden pro Tag zur Verf\u00fcgung, um die G\u00e4ste nach Monaco und zur\u00fcck zu fahren).<br \/>\nLebensmittel und Getr\u00e4nke gegen Aufpreis<\/p>\n<p>Enthaltene Dienstleistungen:<\/p>\n<p>Willkommensgetr\u00e4nke mit Begr\u00fc\u00dfung &#8211; Abholung und R\u00fcckfahrt vom Flughafen Nizza.<br \/>\nT\u00e4gliche Reinigung<br \/>\nT\u00e4glicher Zimmervorbereitungsservice<br \/>\nWechsel von Handt\u00fcchern<br \/>\nWechseln der Bettw\u00e4sche<br \/>\nReinigung der G\u00e4stew\u00e4sche &#8211; Reinigung des Pools<br \/>\nPflege des Gartens<br \/>\nWIFI<br \/>\nAlle Rechnungen f\u00fcr \u00f6ffentliche Dienstleistungen<br \/>\nVersorgung.<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","secteurs":[5862,5862,5861,5923],"service":[90,92,102,147,69,359,70,97,103,82,133,71,93,1292,83,1383,84,94],"tags":[],"type_de_bien":[5856,5856],"type_annonce":[5875,5875],"class_list":{"0":"post-3910269","1":"annonce","2":"type-annonce","3":"status-publish","4":"hentry","5":"secteurs-alpes-maritimes-de","7":"secteurs-france-de","8":"secteurs-roquebrune-cap-martin-de","9":"service-air-conditionne","10":"service-alarme","11":"service-ascenseur","12":"service-barbecue","13":"service-cheminee","14":"service-coffre-fort","15":"service-domotique","16":"service-eclairage-exterieur","17":"service-fibre-optique","18":"service-jacuzzi","19":"service-maison-de-gardien","20":"service-piscine","21":"service-portail-electrique","22":"service-salle-de-sport","23":"service-sauna","24":"service-service-de-securite","25":"service-spa","26":"service-video-surveillance","27":"type_de_bien-heim","29":"type_annonce-saisonale-vermietung"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Roquebrune-Cap-Martin - Luxusvilla mit 5 Schlafzimmern, 5 Minuten von Monaco entfernt - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roquebrune-Cap-Martin - Luxusvilla mit 5 Schlafzimmern, 5 Minuten von Monaco entfernt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T11:36:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/\",\"url\":\"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/\",\"name\":\"Roquebrune-Cap-Martin - Luxusvilla mit 5 Schlafzimmern, 5 Minuten von Monaco entfernt - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\"},\"datePublished\":\"2024-02-07T17:38:31+00:00\",\"dateModified\":\"2026-03-20T11:36:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roquebrune-Cap-Martin &#8211; Luxusvilla mit 5 Schlafzimmern, 5 Minuten von Monaco entfernt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roquebrune-Cap-Martin - Luxusvilla mit 5 Schlafzimmern, 5 Minuten von Monaco entfernt - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/","og_locale":"de_DE","og_type":"article","og_title":"Roquebrune-Cap-Martin - Luxusvilla mit 5 Schlafzimmern, 5 Minuten von Monaco entfernt","og_url":"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-03-20T11:36:01+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/","url":"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/","name":"Roquebrune-Cap-Martin - Luxusvilla mit 5 Schlafzimmern, 5 Minuten von Monaco entfernt - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/de\/#website"},"datePublished":"2024-02-07T17:38:31+00:00","dateModified":"2026-03-20T11:36:01+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/de\/annonce\/roquebrune-cap-martin-luxusvilla-mit-5-schlafzimmern-5-minuten-von-monaco-entfernt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/de\/"},{"@type":"ListItem","position":2,"name":"Roquebrune-Cap-Martin &#8211; Luxusvilla mit 5 Schlafzimmern, 5 Minuten von Monaco entfernt"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/de\/#website","url":"https:\/\/www.carlton-international.com\/de\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/de\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/de\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/annonce\/3910269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/types\/annonce"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/media?parent=3910269"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/secteurs?post=3910269"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/service?post=3910269"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/tags?post=3910269"},{"taxonomy":"type_de_bien","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/type_de_bien?post=3910269"},{"taxonomy":"type_annonce","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/type_annonce?post=3910269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}