{"id":3773027,"date":"2022-04-13T17:53:28","date_gmt":"2022-04-13T15:53:28","guid":{"rendered":"https:\/\/www.carlton-international.com\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/"},"modified":"2026-04-17T00:12:32","modified_gmt":"2026-04-16T22:12:32","slug":"le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael","status":"publish","type":"annonce","link":"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/","title":{"rendered":"Le Trayas Moderne Villa mit Panorama-Meerblick, Saint Raphael"},"content":{"rendered":"<p>Im Herzen des Esterel-Gebirges, in einer geschlossenen Anlage nur 10 Minuten vom Dorf Th\u00e9oule-sur-Mer entfernt, liegt diese wundersch\u00f6ne, moderne Villa, die komplett renoviert wurde. Sie bietet einen atemberaubenden Blick auf das Meer, die Bucht von Cannes und die Inseln.<\/p>\n<p>Die auf zwei Ebenen errichtete Villa besteht im Erdgeschoss aus einem ger\u00e4umigen Wohnzimmer mit einem zentralen Kamin, das dank seiner gro\u00dfen Fenster, die einen au\u00dfergew\u00f6hnlichen Panoramablick auf das Meer enth\u00fcllen, lichtdurchflutet ist. Die voll ausgestattete amerikanische K\u00fcche umfasst einen Essbereich und eine Speisekammer. Das Ensemble \u00f6ffnet sich zu den gro\u00dfen Terrassen mit Panoramablick. ref 11945<\/p>\n<p>Im Gartengeschoss befinden sich drei Schlafzimmer mit eigenem Duschbad, darunter eine Master-Suite mit Ankleidezimmer und Badewanne, die sich zu Terrassen hin \u00f6ffnen, die zu einem gro\u00dfen Pool f\u00fchren. Auf dieser Ebene befinden sich au\u00dferdem eine ger\u00e4umige Waschk\u00fcche, ein Weinkeller und eine G\u00e4stetoilette sowie ein separates Apartment mit Toilette und Dusche.<\/p>\n<p>Auf einem 1173 m\u00b2 gro\u00dfen Grundst\u00fcck gelegen, umfasst das Anwesen au\u00dferdem ein separates Studio und geschlossene Parkpl\u00e4tze. Ref 11945<\/p>\n<p>Die durchschnittlichen Energiekosten im Jahr 2021 betragen zwischen 850 \u20ac und 1220 \u20ac pro Jahr.<br \/>\nDie Maklergeb\u00fchren gehen zu Lasten des Verk\u00e4ufers.<\/p>\n<p>Informationen \u00fcber die Risiken, denen diese Immobilie ausgesetzt ist, finden Sie auf der Website G\u00e9orisques http:\/\/www.georisques.gouv.fr<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","secteurs":[5862,9302,9302,5862,5861,3368,1683,5911],"service":[90,92,96,69,91,72,97,73,71,93,152,1294,88],"tags":[7896,7897,7895,8829,164,99,4084,4081,4087,89,4545,78,4546],"type_de_bien":[5856,5856],"type_annonce":[5864,5864],"class_list":{"0":"post-3773027","1":"annonce","2":"type-annonce","3":"status-publish","4":"hentry","5":"secteurs-alpes-maritimes-de","6":"secteurs-alpes-maritimes-en-11","9":"secteurs-france-de","10":"secteurs-france-en","11":"secteurs-theoule-sur-mer-en","12":"secteurs-theoule-sur-mer-de","13":"service-air-conditionne","14":"service-alarme","15":"service-arrosage","16":"service-cheminee","17":"service-cloture","18":"service-double-vitrage","19":"service-eclairage-exterieur","20":"service-fenetres-coulissantes","21":"service-piscine","22":"service-portail-electrique","23":"service-stores","24":"service-thermostat-connecte","25":"service-videophone","26":"tags-diagnostiques-techniques","27":"tags-passeport-id","28":"tags-site-carlton-international","29":"tags-vue-mer","30":"tags-aucun-vis-a-vis","31":"tags-cadre-silencieux","32":"tags-contemporaine","33":"tags-domaine-ferme","34":"tags-domaine-securise","35":"tags-mer","36":"tags-plateformes","37":"tags-quartier-residentiel","38":"tags-reseaux-sociaux","39":"type_de_bien-heim","41":"type_annonce-kaufen"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Trayas Moderne Villa mit Panorama-Meerblick, Saint Raphael - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Trayas Moderne Villa mit Panorama-Meerblick, Saint Raphael\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T22:12:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/\",\"url\":\"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/\",\"name\":\"Le Trayas Moderne Villa mit Panorama-Meerblick, Saint Raphael - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\"},\"datePublished\":\"2022-04-13T15:53:28+00:00\",\"dateModified\":\"2026-04-16T22:12:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Trayas Moderne Villa mit Panorama-Meerblick, Saint Raphael\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Trayas Moderne Villa mit Panorama-Meerblick, Saint Raphael - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/","og_locale":"de_DE","og_type":"article","og_title":"Le Trayas Moderne Villa mit Panorama-Meerblick, Saint Raphael","og_url":"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-04-16T22:12:32+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/","url":"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/","name":"Le Trayas Moderne Villa mit Panorama-Meerblick, Saint Raphael - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/de\/#website"},"datePublished":"2022-04-13T15:53:28+00:00","dateModified":"2026-04-16T22:12:32+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/de\/annonce\/le-trayas-moderne-villa-mit-panorama-meerblick-saint-raphael\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/de\/"},{"@type":"ListItem","position":2,"name":"Le Trayas Moderne Villa mit Panorama-Meerblick, Saint Raphael"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/de\/#website","url":"https:\/\/www.carlton-international.com\/de\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/de\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/de\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/annonce\/3773027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/types\/annonce"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/media?parent=3773027"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/secteurs?post=3773027"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/service?post=3773027"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/tags?post=3773027"},{"taxonomy":"type_de_bien","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/type_de_bien?post=3773027"},{"taxonomy":"type_annonce","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/type_annonce?post=3773027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}