{"id":3485991,"date":"2024-08-06T08:56:59","date_gmt":"2024-08-06T06:56:59","guid":{"rendered":"https:\/\/www.carlton-international.com\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/"},"modified":"2026-03-20T12:30:25","modified_gmt":"2026-03-20T11:30:25","slug":"cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick","status":"publish","type":"annonce","link":"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/","title":{"rendered":"Cap d&#8217;Antibes &#8211; Villa mit 5 Schlafzimmern &#8211; Pool &#8211; Meerblick"},"content":{"rendered":"<p>Am prestigetr\u00e4chtigen Westhang des Cap d&#8217;Antibes, in absolut ruhiger Lage, nur wenige Schritte von den kristallklaren Str\u00e4nden und den Hotels Eden Roc &amp; Belles Rives entfernt, bietet Ihnen Carlton International diese elegante Villa mit Meerblick.<\/p>\n<p>Die Villa erstreckt sich \u00fcber zwei Ebenen und bietet ein gro\u00dfes, helles Doppelwohnzimmer, eine Veranda mit Panoramablick, eine offene K\u00fcche der Spitzenklasse, f\u00fcnf wundersch\u00f6ne Schlafzimmer en suite, einen Fitnessraum, eine Garage, einen Landschaftsgarten und einen herrlichen Salzwasserpool.<\/p>\n<p>Ein diskretes und raffiniertes Refugium im Herzen der Riviera, 25 Minuten von Cannes und 30 Minuten vom Flughafen Nizza entfernt.<\/p>\n<p>Risikoinformationen: www.georisques.gouv.fr<br \/>\nHonorar zu Lasten des Verk\u00e4ufers.<br \/>\nRef. 15385<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","secteurs":[9302,5862,5862,1617,5863,5861,3368],"service":[146,90,92,69,103,71,1292,84],"tags":[7896,7895,118,113,117,99,4083,141,89,4546,3898],"type_de_bien":[5856,5856],"type_annonce":[5864,5864],"class_list":{"0":"post-3485991","1":"annonce","2":"type-annonce","3":"status-publish","4":"hentry","5":"secteurs-alpes-maritimes-en-11","6":"secteurs-alpes-maritimes-de","8":"secteurs-antibes-en","9":"secteurs-antibes-de","10":"secteurs-france-de","11":"secteurs-france-en","12":"service-abri-de-voiture","13":"service-air-conditionne","14":"service-alarme","15":"service-cheminee","16":"service-fibre-optique","17":"service-piscine","18":"service-salle-de-sport","19":"service-spa","20":"tags-diagnostiques-techniques","21":"tags-site-carlton-international","22":"tags-a-pied-des-commerces","23":"tags-a-pied-des-plages","24":"tags-a-pied-du-village","25":"tags-cadre-silencieux","26":"tags-emplacement-exceptionnel","27":"tags-espace-fitness","28":"tags-mer","29":"tags-reseaux-sociaux","30":"tags-spa","31":"type_de_bien-heim","33":"type_annonce-kaufen"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cap d&#039;Antibes - Villa mit 5 Schlafzimmern - Pool - Meerblick - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cap d&#039;Antibes - Villa mit 5 Schlafzimmern - Pool - Meerblick\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T11:30:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/\",\"url\":\"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/\",\"name\":\"Cap d'Antibes - Villa mit 5 Schlafzimmern - Pool - Meerblick - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\"},\"datePublished\":\"2024-08-06T06:56:59+00:00\",\"dateModified\":\"2026-03-20T11:30:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cap d&rsquo;Antibes &#8211; Villa mit 5 Schlafzimmern &#8211; Pool &#8211; Meerblick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cap d'Antibes - Villa mit 5 Schlafzimmern - Pool - Meerblick - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/","og_locale":"de_DE","og_type":"article","og_title":"Cap d'Antibes - Villa mit 5 Schlafzimmern - Pool - Meerblick","og_url":"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-03-20T11:30:25+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/","url":"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/","name":"Cap d'Antibes - Villa mit 5 Schlafzimmern - Pool - Meerblick - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/de\/#website"},"datePublished":"2024-08-06T06:56:59+00:00","dateModified":"2026-03-20T11:30:25+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/de\/annonce\/cap-dantibes-villa-mit-5-schlafzimmern-pool-meerblick\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/de\/"},{"@type":"ListItem","position":2,"name":"Cap d&rsquo;Antibes &#8211; Villa mit 5 Schlafzimmern &#8211; Pool &#8211; Meerblick"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/de\/#website","url":"https:\/\/www.carlton-international.com\/de\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/de\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/de\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/annonce\/3485991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/types\/annonce"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/media?parent=3485991"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/secteurs?post=3485991"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/service?post=3485991"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/tags?post=3485991"},{"taxonomy":"type_de_bien","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/type_de_bien?post=3485991"},{"taxonomy":"type_annonce","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/type_annonce?post=3485991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}