{"id":2124725,"date":"2023-06-17T10:55:30","date_gmt":"2023-06-17T08:55:30","guid":{"rendered":"https:\/\/www.carlton-international.com\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/"},"modified":"2026-04-08T00:11:06","modified_gmt":"2026-04-07T22:11:06","slug":"new-contemporary-villa-at-the-entrance-to-saint-tropez","status":"publish","type":"annonce","link":"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/","title":{"rendered":"New, contemporary villa at the entrance to Saint-Tropez"},"content":{"rendered":"<p>This new luxury villa is ideally located in the SINOPOLIS estate at the entrance to Saint-Tropez and offers a beautiful sea view, in a refined design.<\/p>\n<p>The villa features 4 bedrooms, a spacious living room, a fully-equipped kitchen and a cinema room, as well as a basement bar and billiards table, and a dormitory room.<\/p>\n<p>A heated swimming pool, double garage and pool house complete this delightful villa.<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","secteurs":[5861,5861,3368,6014,6014,1661,3370,5905,5905],"service":[90,92,1295,71,93,87,95,94,88,101],"tags":[4084,141,140,89,2239,78],"type_de_bien":[5856,5856],"type_annonce":[5875,5875],"class_list":{"0":"post-2124725","1":"annonce","2":"type-annonce","3":"status-publish","4":"hentry","5":"secteurs-france-de","7":"secteurs-france-en","8":"secteurs-gassin-de","10":"secteurs-gassin-en","11":"secteurs-var-en","12":"secteurs-var-de","14":"service-air-conditionne","15":"service-alarme","16":"service-cinema","17":"service-piscine","18":"service-portail-electrique","19":"service-porte-blindee","20":"service-stores-electriques","21":"service-video-surveillance","22":"service-videophone","23":"service-volets-roulants-electriques","24":"tags-contemporaine","25":"tags-espace-fitness","26":"tags-home-cinema","27":"tags-mer","28":"tags-piscine-chauffee","29":"tags-quartier-residentiel","30":"type_de_bien-heim","32":"type_annonce-saisonale-vermietung"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>New, contemporary villa at the entrance to Saint-Tropez - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New, contemporary villa at the entrance to Saint-Tropez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T22:11:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/\",\"url\":\"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/\",\"name\":\"New, contemporary villa at the entrance to Saint-Tropez - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\"},\"datePublished\":\"2023-06-17T08:55:30+00:00\",\"dateModified\":\"2026-04-07T22:11:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New, contemporary villa at the entrance to Saint-Tropez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"New, contemporary villa at the entrance to Saint-Tropez - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/","og_locale":"de_DE","og_type":"article","og_title":"New, contemporary villa at the entrance to Saint-Tropez","og_url":"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-04-07T22:11:06+00:00","twitter_card":"summary_large_image","twitter_site":"@CarltonInter","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/","url":"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/","name":"New, contemporary villa at the entrance to Saint-Tropez - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/de\/#website"},"datePublished":"2023-06-17T08:55:30+00:00","dateModified":"2026-04-07T22:11:06+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/de\/annonce\/new-contemporary-villa-at-the-entrance-to-saint-tropez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/de\/"},{"@type":"ListItem","position":2,"name":"New, contemporary villa at the entrance to Saint-Tropez"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/de\/#website","url":"https:\/\/www.carlton-international.com\/de\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/de\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/de\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/annonce\/2124725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/types\/annonce"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/media?parent=2124725"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/secteurs?post=2124725"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/service?post=2124725"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/tags?post=2124725"},{"taxonomy":"type_de_bien","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/type_de_bien?post=2124725"},{"taxonomy":"type_annonce","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/type_annonce?post=2124725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}