{"id":4310585,"date":"2026-02-25T08:37:08","date_gmt":"2026-02-25T07:37:08","guid":{"rendered":"https:\/\/www.carlton-international.com\/?post_type=agence&#038;p=4310585"},"modified":"2026-03-10T03:59:03","modified_gmt":"2026-03-10T02:59:03","slug":"antibes","status":"publish","type":"agence","link":"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/","title":{"rendered":"Antibes"},"content":{"rendered":"","protected":false},"featured_media":3223830,"menu_order":0,"template":"","secteurs":[],"class_list":["post-4310585","agence","type-agence","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Antibes - Carlton International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antibes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlton International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T02:59:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/01\/Antibes-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarltonInter\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/\",\"url\":\"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/\",\"name\":\"Antibes - Carlton International\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/01\/Antibes-1-scaled.jpg\",\"datePublished\":\"2026-02-25T07:37:08+00:00\",\"dateModified\":\"2026-03-10T02:59:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/#primaryimage\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/01\/Antibes-1-scaled.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/01\/Antibes-1-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"Antibes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.carlton-international.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antibes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#website\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"name\":\"Carlton International\",\"description\":\"Luxury Real Estate in France and Internationally\",\"publisher\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\"},\"alternateName\":\"Carlton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#organization\",\"name\":\"Carlton International\",\"alternateName\":\"Carlton\",\"url\":\"https:\/\/www.carlton-international.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"contentUrl\":\"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg\",\"width\":240,\"height\":240,\"caption\":\"Carlton International\"},\"image\":{\"@id\":\"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/\",\"https:\/\/x.com\/CarltonInter\",\"https:\/\/www.instagram.com\/carlton.international\/\",\"https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/\",\"https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Antibes - Carlton International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/","og_locale":"de_DE","og_type":"article","og_title":"Antibes","og_url":"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/","og_site_name":"Carlton International","article_publisher":"https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","article_modified_time":"2026-03-10T02:59:03+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/01\/Antibes-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CarltonInter","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/","url":"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/","name":"Antibes - Carlton International","isPartOf":{"@id":"https:\/\/www.carlton-international.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/#primaryimage"},"image":{"@id":"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/01\/Antibes-1-scaled.jpg","datePublished":"2026-02-25T07:37:08+00:00","dateModified":"2026-03-10T02:59:03+00:00","breadcrumb":{"@id":"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlton-international.com\/de\/agence\/antibes\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/#primaryimage","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/01\/Antibes-1-scaled.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2023\/01\/Antibes-1-scaled.jpg","width":1920,"height":2560,"caption":"Antibes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlton-international.com\/de\/agence\/antibes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carlton-international.com\/de\/"},{"@type":"ListItem","position":2,"name":"Antibes"}]},{"@type":"WebSite","@id":"https:\/\/www.carlton-international.com\/de\/#website","url":"https:\/\/www.carlton-international.com\/de\/","name":"Carlton International","description":"Luxury Real Estate in France and Internationally","publisher":{"@id":"https:\/\/www.carlton-international.com\/de\/#organization"},"alternateName":"Carlton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlton-international.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.carlton-international.com\/de\/#organization","name":"Carlton International","alternateName":"Carlton","url":"https:\/\/www.carlton-international.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","contentUrl":"https:\/\/www.carlton-international.com\/wp-content\/uploads\/2024\/10\/logo-square-1.jpg","width":240,"height":240,"caption":"Carlton International"},"image":{"@id":"https:\/\/www.carlton-international.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CarltonInternationalRealEstate\/","https:\/\/x.com\/CarltonInter","https:\/\/www.instagram.com\/carlton.international\/","https:\/\/www.linkedin.com\/company\/carlton-international\/mycompany\/","https:\/\/www.youtube.com\/channel\/UC45DFaSawRRikZFLqr2C_XQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/agence\/4310585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/agence"}],"about":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/types\/agence"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/media\/3223830"}],"wp:attachment":[{"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/media?parent=4310585"}],"wp:term":[{"taxonomy":"secteurs","embeddable":true,"href":"https:\/\/www.carlton-international.com\/de\/wp-json\/wp\/v2\/secteurs?post=4310585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}